{"id":46916,"date":"2023-07-18T10:00:00","date_gmt":"2023-07-18T13:00:00","guid":{"rendered":"https:\/\/www.agendor.com.br\/blog\/?p=46916"},"modified":"2023-11-22T14:51:18","modified_gmt":"2023-11-22T17:51:18","slug":"tipos-de-prospeccao","status":"publish","type":"post","link":"https:\/\/www.agendor.com.br\/blog\/tipos-de-prospeccao\/","title":{"rendered":"Os principais tipos de prospec\u00e7\u00e3o com dicas de estrat\u00e9gias!"},"content":{"rendered":"\n<p>Est\u00e1 dif\u00edcil conseguir novos clientes e melhorar a escalabilidade da empresa? Saiba que voc\u00ea pode implementar diversos tipos de prospec\u00e7\u00e3o e ampliar a sua busca por novos contatos e possibilidades de neg\u00f3cios.<\/p>\n\n\n\n<h3 class=\"titleKeyTakeaways\">Principais aprendizados deste artigo:<\/h3>\n\n\n\n<ul class=\"keyTakeaways\"><li>Os principais tipos de prospec\u00e7\u00e3o s\u00e3o: ativa (outbound), passiva (inbound), de canais e marketing de refer\u00eancia, com indica\u00e7\u00f5es de <a href=\"https:\/\/www.agendor.com.br\/blog\/clientes-satisfeitos\/?cta=blog-principais-aprendizadosr\" target=\"_blank\" rel=\"noreferrer noopener\">clientes satisfeitos<\/a>, amigos, parceiros e familiares.<\/li><li>A prospec\u00e7\u00e3o ativa \u00e9 quando o vendedor aborda o lead sem que ele tenha mostrado interesse na empresa e suas solu\u00e7\u00f5es. Pode ser feita <a href=\"https:\/\/www.agendor.com.br\/blog\/como-vender-por-telefone-dicas\/?cta=blog-principais-aprendizados\" target=\"_blank\" rel=\"noreferrer noopener\">por telefone<\/a>, envio de e-mail ou mensagem e visita.<\/li><li>A prospec\u00e7\u00e3o passiva \u00e9 quando o pr\u00f3prio lead interage com a marca e fornece seus dados em troca de receber algum material rico, como <a href=\"https:\/\/www.agendor.com.br\/blog\/o-que-e-ebook\/?cta=blog-principais-aprendizados\" target=\"_blank\" rel=\"noreferrer noopener\">e-books<\/a>, infogr\u00e1ficos, pesquisas, webinars e videoaulas.<\/li><li>Para escolher a melhor forma de prospec\u00e7\u00e3o \u00e9 preciso identificar o perfil do seu cliente ideal e estudar tudo sobre ele: necessidades, expectativas, desejos, problemas, <a href=\"https:\/\/www.agendor.com.br\/blog\/comportamento-de-compra\/?cta=blog-principais-aprendizados\" target=\"_blank\" rel=\"noreferrer noopener\">comportamento de compra<\/a> etc.<\/li><li>Baixe gr\u00e1tis nosso e-book e domine tudo sobre prospectar clientes: <a href=\"https:\/\/materiais.agendor.com.br\/guia-da-prospeccao?cta=blog-principais-aprendizados\" target=\"_blank\" rel=\"noreferrer noopener\">Guia: como prospectar novos clientes e gerar leads qualificados<\/a>. E, para praticar os aprendizados, inscreva-se e <a href=\"https:\/\/web.agendor.com.br\/cadastro\/?pid=104&amp;cta=blog-principais-aprendizados\" target=\"_blank\" rel=\"noreferrer noopener\">teste gratuitamente o CRM do Agendor<\/a>!<\/li><\/ul>\n\n\n\n<p>Por\u00e9m, antes de sair \u201catirando para tudo que \u00e9 lado\u201d, saiba que cada forma de prospec\u00e7\u00e3o exige uma pesquisa e um planejamento estrat\u00e9gico diferenciado. As t\u00e1ticas utilizadas em uma liga\u00e7\u00e3o s\u00e3o completamente diferentes das usadas em redes sociais e sites, por exemplo.<\/p>\n\n\n\n<p>O importante \u00e9 conhecer as variadas maneiras de atrair novos prospects e sair na frente da concorr\u00eancia. J\u00e1 adiantamos que, mesmo que suas a\u00e7\u00f5es sejam offline, um dos principais pilares de uma prospec\u00e7\u00e3o eficaz \u00e9 o uso de sistemas tecnol\u00f3gicos inteligentes, especialmente se realiza <strong>vendas B2B e mais complexas<\/strong>.<\/p>\n\n\n\n<p>Eles coletam e integram dados essenciais para orientar os pr\u00f3ximos passos da equipe de marketing ou de vendas, sinalizando a etapa da jornada de compra em que cada lead est\u00e1.<\/p>\n\n\n\n<p>Vamos descobrir como aumentar a taxa de convers\u00e3o realizando uma prospec\u00e7\u00e3o eficiente? Continue a leitura e conhe\u00e7a os principais tipos de prospectar, exemplos e dicas para potencializar seus resultados!<\/p>\n\n\n\n<h2>Quais s\u00e3o os principais tipos de prospec\u00e7\u00e3o de clientes?<\/h2>\n\n\n\n<p>Os principais tipos de prospec\u00e7\u00e3o de clientes s\u00e3o: <strong>outbound (ativa), inbound (passiva), canais e marketing de refer\u00eancia<\/strong>, que inclui indica\u00e7\u00f5es de parceiros comerciais, amigos e familiares, al\u00e9m do boca a boca de consumidores satisfeitos.<\/p>\n\n\n\n<p>Com o avan\u00e7o da tecnologia, a <a href=\"https:\/\/www.agendor.com.br\/blog\/prospeccao-de-vendas\/\" target=\"_blank\" rel=\"noreferrer noopener\">prospec\u00e7\u00e3o<\/a> porta a porta ficou para tr\u00e1s e o um universo de possibilidades de atrair potenciais clientes se abriu.<\/p>\n\n\n\n<p>Conhe\u00e7a as caracter\u00edsticas de cada tipo de prospec\u00e7\u00e3o!<\/p>\n\n\n\n<h3>Prospec\u00e7\u00e3o outbound<\/h3>\n\n\n\n<p>A <a href=\"https:\/\/www.agendor.com.br\/blog\/prospeccao-outbound\/\" target=\"_blank\" rel=\"noreferrer noopener\">prospec\u00e7\u00e3o outbound<\/a> nada mais \u00e9 do que a <strong>prospec\u00e7\u00e3o ativa<\/strong>. Ou seja, quando o vendedor entra em contato e aborda a pessoa sem que ela tenha demonstrado interesse ou conhecimento da marca e suas solu\u00e7\u00f5es. Isso pode acontecer por meio de liga\u00e7\u00e3o, e-mail, mensagens ou at\u00e9 mesmo visita.<\/p>\n\n\n\n<p>A prospec\u00e7\u00e3o outbound n\u00e3o \u00e9 baseada em achismos, ela envolve bastante pesquisa do setor e <a href=\"https:\/\/www.agendor.com.br\/blog\/como-segmentar-o-mercado\/\" target=\"_blank\" rel=\"noreferrer noopener\">segmenta\u00e7\u00e3o do mercado<\/a> para perder tempo e abordar leads n\u00e3o qualificados.<\/p>\n\n\n\n<p>Para encontrar potenciais clientes, o vendedor utiliza, por exemplo:<\/p>\n\n\n\n<ul><li>pesquisa no Google;<\/li><li>pesquisa em redes sociais, especialmente Linkedin;<\/li><li>associa\u00e7\u00f5es de com\u00e9rcio;<\/li><li>cat\u00e1logos especializados do setor;<\/li><li>not\u00edcias e informa\u00e7\u00f5es sobre o segmento e o mercado;<\/li><li>sistemas de intelig\u00eancia artificial que sugerem leads compat\u00edveis com seu p\u00fablico-alvo.<\/li><\/ul>\n\n\n\n<p>Saiba mais: <a href=\"https:\/\/www.agendor.com.br\/blog\/venda-ativa-prospeccao\/\" target=\"_blank\" rel=\"noreferrer noopener\">Prospec\u00e7\u00e3o ativa: 14 dicas pra captar clientes e aumentar seus ganhos<\/a><\/p>\n\n\n\n<h3>Prospec\u00e7\u00e3o inbound<\/h3>\n\n\n\n<p>A <a href=\"https:\/\/www.agendor.com.br\/blog\/beneficios-do-inbound-marketing\/\" target=\"_blank\" rel=\"noreferrer noopener\">prospec\u00e7\u00e3o inbound<\/a> <strong>ou passiva<\/strong> \u00e9 quando os clientes interagem com a marca por meio de variadas plataformas digitais. As t\u00e1ticas de inbound marketing atraem potenciais clientes por meio da troca de informa\u00e7\u00f5es sobre eles por algum material \u00fatil, como e-book, loge webinars, ou demonstra\u00e7\u00f5es gratuitas de seu produto ou servi\u00e7o.<\/p>\n\n\n\n<p>Ou seja: ao se cadastrar em um formul\u00e1rio para baixar um e-book, acessar uma videoaula ou conferir uma pesquisa sobre o setor, o lead informa seus principais dados.<\/p>\n\n\n\n<p>A equipe de marketing utiliza essas informa\u00e7\u00f5es para nutrir o lead, enviando e-mails com materiais educativos, por exemplo. E, assim, vai guiando o prospect pelas <a href=\"https:\/\/www.agendor.com.br\/blog\/o-que-e-funil-de-vendas\/\" target=\"_blank\" rel=\"noreferrer noopener\">etapas do funil de venda<\/a> at\u00e9 que esteja pronto para comprar.<\/p>\n\n\n\n<p>Caso ele j\u00e1 esteja em uma etapa avan\u00e7ada, apenas pesquisando a melhor empresa para adquirir seu produto ou servi\u00e7o, \u00e9 enviado \u00e0 equipe de vendas para iniciar o processo de envio de proposta e negocia\u00e7\u00e3o.<\/p>\n\n\n\n<h3>Prospec\u00e7\u00e3o por canais<\/h3>\n\n\n\n<p>Esse tipo de prospectar clientes acontece por meio da <strong>identifica\u00e7\u00e3o dos canais mais eficazes para atrair novos contatos<\/strong>. Depois, a empresa concentra todos seus esfor\u00e7os e suas estrat\u00e9gias neles.<\/p>\n\n\n\n<p>A <a href=\"https:\/\/www.agendor.com.br\/blog\/canais-de-venda\/\" target=\"_blank\" rel=\"noreferrer noopener\">prospec\u00e7\u00e3o por canais<\/a> \u00e9 realizada na maior parte das vezes por parcerias com outras marcas, escalando suas vendas e reduzindo custos com prospec\u00e7\u00e3o. Afinal, o parceiro \u00e9 o respons\u00e1vel por atrair e conquistar leads e fechar a venda em troca de comissionamento.<\/p>\n\n\n\n<h3>Prospec\u00e7\u00e3o por marketing de refer\u00eancia<\/h3>\n\n\n\n<p>J\u00e1 a prospec\u00e7\u00e3o por marketing de refer\u00eancia \u00e9 justamente o que o pr\u00f3prio nome indica: <strong>estrat\u00e9gia que atrai novos contatos por meio da indica\u00e7\u00e3o de clientes satisfeitos e at\u00e9 mesmo amigos, familiares e parceiros<\/strong>, como fornecedores.<\/p>\n\n\n\n<p>Por isso, invista na aplica\u00e7\u00e3o de <a href=\"https:\/\/www.agendor.com.br\/blog\/pesquisa-de-satisfacao-do-cliente\/\" target=\"_blank\" rel=\"noreferrer noopener\">pesquisas de satisfa\u00e7\u00e3o do cliente<\/a> regularmente para identificar quem s\u00e3o os promotores da sua marca e podem indicar novas oportunidades de neg\u00f3cio.<\/p>\n\n\n\n<p>Para potencializar a quantidade de resposta da pesquisa, ofere\u00e7a algo em troca, como descontos, e-books exclusivos, brindes ou pontos de fidelidade.<\/p>\n\n\n\n<h2>Quais os tipos de prospec\u00e7\u00e3o ativa?<\/h2>\n\n\n\n<p>Os tipos de prospec\u00e7\u00e3o ativa se dividem entre <strong>online e offline<\/strong>. Engana-se quem pensa que essa forma mais tradicional de prospectar clientes \u00e9 feita apenas por liga\u00e7\u00f5es (cold calling) e e-mails (cold mailing). O vendedor tamb\u00e9m pode abordar novos contatos por mensagens no WhatsApp ou pelas redes sociais, como o Linkedin.<\/p>\n\n\n\n<p>Conhe\u00e7a as formas de prospec\u00e7\u00e3o ativa mais usadas atualmente:<\/p>\n\n\n\n<ul><li><strong>cold mailing<\/strong>: chamado de e-mail frio, ele busca realizar a primeira abordagem com o contato por e-mail, sem que ele necessariamente conhe\u00e7a a marca e suas solu\u00e7\u00f5es;<\/li><li><strong>cold calling<\/strong>: sabe o famoso \u201ctelemarketing\u201d? Ele \u00e9 uma <a href=\"https:\/\/www.agendor.com.br\/blog\/significado-cold-calling\/\" target=\"_blank\" rel=\"noreferrer noopener\">cold calling<\/a>. Ou seja, liga para algu\u00e9m se a pessoa ter interagido com o neg\u00f3cio. Muitos consideram essa t\u00e9cnica muito invasiva, por\u00e9m, feita de modo equilibrado, pode ter bons resultados;<\/li><li><strong>redes sociais<\/strong>: envio de mensagens para pessoas, principalmente no Linkedin, que possuem o perfil do cliente ideal da sua empresa. A ideia \u00e9 apresentar o neg\u00f3cio e como ele pode ajudar o lead a resolver seus problemas.<\/li><\/ul>\n\n\n\n<p>As t\u00e9cnicas de outbound s\u00e3o bastante utilizadas por empresas B2B de m\u00e9dio e grande porte, com valor mais alto do ticket m\u00e9dio e vendas mais complexas. Isso porque a opera\u00e7\u00e3o de \u201cir atr\u00e1s\u201d do cliente sai mais cara do que a prospec\u00e7\u00e3o inbound.<\/p>\n\n\n\n<p>Continue aprendendo: <a href=\"https:\/\/www.agendor.com.br\/blog\/exemplos-de-email-de-prospeccao\/\" target=\"_blank\" rel=\"noreferrer noopener\">Email de prospec\u00e7\u00e3o: 5 exemplos e 7 dicas pr\u00e1ticas para criar o seu!<\/a><\/p>\n\n\n\n<h2>Quais os tipos de prospec\u00e7\u00e3o passiva?<\/h2>\n\n\n\n<p>As formas mais utilizadas de prospec\u00e7\u00e3o passiva s\u00e3o: <strong>site institucional, blog, landing page, redes sociais, e-mail marketing e an\u00fancios em plataformas digitais<\/strong>. Isto \u00e9: esse tipo oferece outras op\u00e7\u00f5es menos invasivas, mais baratas e <a href=\"https:\/\/www.agendor.com.br\/blog\/como-mensurar-e-apresentar-os-resultados-de-prospeccao-de-clientes\/\" target=\"_blank\" rel=\"noreferrer noopener\">mais f\u00e1ceis de serem mensuradas<\/a>.<\/p>\n\n\n\n<p>Veja quais os tipos de prospec\u00e7\u00e3o passiva podem ser usados na sua empresa:<\/p>\n\n\n\n<ul><li><strong>site da marca<\/strong>: \u00e9 a vitrine da sua empresa e precisa ser objetivo e impactante. Deixe um espa\u00e7o para cadastro de newsletter, pedido de or\u00e7amento e d\u00favidas. Assim, o lead insere seus dados e inicia o relacionamento com o neg\u00f3cio;<\/li><li><strong>marketing de conte\u00fado<\/strong>: tem a finalidade de produzir conte\u00fados e materiais relevantes e \u00fateis para o lead de uma empresa, atraindo potenciais clientes que possam se interessar pelos produtos ou servi\u00e7os. Pode ser feito por blog, e-mail marketing, redes sociais, landing page, Youtube etc;<\/li><li><strong>redes sociais:<\/strong> \u00e9 essencial a marca marcar presen\u00e7a nas redes sociais preferidas de sua persona. Trabalhe sua autoridade no mercado e ofere\u00e7a conte\u00fados \u00fateis;<\/li><li><strong>e-mail marketing<\/strong>: quando o lead fornece seu e-mail no cadastro, consentiu com o recebimento de e-mails da sua empresa. Aproveite essa oportunidade e envie materiais educativos de forma equilibrada. N\u00e3o se esque\u00e7a de segmentar sua base de contatos para tornar as campanhas e a\u00e7\u00f5es mais assertivas.<\/li><\/ul>\n\n\n\n<p>Confira mais dicas certeiras!<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img src=\"https:\/\/lh6.googleusercontent.com\/Kl4n7_j6IWbgifFmNeMizG2Yiu3LY956HXwa7rlNeW9BDIsyOZPNc18fu05jjBEkCqWtsZRGVh0aMayIkW3vCYpncjFMK9pJVmDLIY4hje3sjmBCizZJCZAWmrsQLFgr1088QIPfbcVqHEYC97xIpUg\" alt=\"\"\/><\/figure>\n\n\n\n<h2>Como escolher a melhor forma de prospec\u00e7\u00e3o?<\/h2>\n\n\n\n<p>Para escolher a melhor forma de prospec\u00e7\u00e3o para sua organiza\u00e7\u00e3o \u00e9<strong> fundamental estudar profundamente seu cliente e identificar seu <\/strong><a href=\"https:\/\/www.agendor.com.br\/blog\/como-definir-o-cliente-ideal\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>perfil de cliente ideal (ICP)<\/strong><\/a>, conhecendo suas necessidades, prefer\u00eancias, expectativas e seu comportamento de compra. Esse passo \u00e9 a chave para entender onde seu lead est\u00e1 e como gosta de ser contactado.<\/p>\n\n\n\n<p>Uma excelente maneira de ter acesso a tanto conhecimento sobre seu p\u00fablico \u00e9 utilizar um software de gest\u00e3o de relacionamento com o cliente. O <a href=\"https:\/\/www.agendor.com.br\/blog\/crm-online\/\" target=\"_blank\" rel=\"noreferrer noopener\">CRM<\/a> coleta, integra e analisa diversos dados valiosos para a marca entender suas personas, seu pipeline e ciclo de venda.<\/p>\n\n\n\n<p>Por\u00e9m, de todo modo, n\u00e3o existe um tipo de prospec\u00e7\u00e3o melhor do que o outro. Veja o or\u00e7amento corporativo e entenda qual a capacidade de investimento nessa \u00e1rea. \u00c9 poss\u00edvel <a href=\"https:\/\/www.agendor.com.br\/blog\/ferramentas-de-prospeccao\/\" target=\"_blank\" rel=\"noreferrer noopener\">utilizar softwares que ajudam a prospectar<\/a>.<\/p>\n\n\n\n<p>A prospec\u00e7\u00e3o multicanal \u00e9 ben\u00e9fica porque amplia o alcance da marca, oferece abordagens distintas e eleva as taxas de respostas. Ou seja: escolher por mais de um tipo de prospec\u00e7\u00e3o nunca deixar\u00e1 sua equipe comercial no \u00f3cio!<br><strong>Aprofunde seus conhecimentos sobre o assunto: baixe gr\u00e1tis nosso <\/strong><a href=\"https:\/\/materiais.agendor.com.br\/guia-da-prospeccao\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Guia: como prospectar novos clientes e gerar leads qualificados<\/strong><\/a><strong>!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e1 dif\u00edcil conseguir novos clientes e melhorar a escalabilidade da empresa? Saiba que voc\u00ea pode implementar diversos tipos de prospec\u00e7\u00e3o e ampliar a sua busca por novos contatos e possibilidades de neg\u00f3cios. Principais aprendizados deste artigo: Os principais tipos de prospec\u00e7\u00e3o s\u00e3o: ativa (outbound), passiva (inbound), de canais e marketing de refer\u00eancia, com indica\u00e7\u00f5es de [&hellip;]<\/p>\n","protected":false},"author":48,"featured_media":46917,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[890],"tags":[795,388],"lista-de-leitura":[],"listas_de_leitura":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.6.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tipos de prospec\u00e7\u00e3o: como escolher o ideal para a empresa?<\/title>\n<meta name=\"description\" content=\"Conhe\u00e7a os principais tipos de prospec\u00e7\u00e3o e quando s\u00e3o mais utilizados. Al\u00e9m disso, veja dicas para optar pelas melhores formas de atrair novos clientes!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.agendor.com.br\/blog\/tipos-de-prospeccao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tipos de prospec\u00e7\u00e3o: como escolher o ideal para a empresa?\" \/>\n<meta property=\"og:description\" content=\"Conhe\u00e7a os principais tipos de prospec\u00e7\u00e3o e quando s\u00e3o mais utilizados. Al\u00e9m disso, veja dicas para optar pelas melhores formas de atrair novos clientes!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.agendor.com.br\/blog\/tipos-de-prospeccao\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Agendor\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/agendor\" \/>\n<meta property=\"article:author\" content=\"https:\/\/s3-sa-east-1.amazonaws.com\/agendor-materiais\/autores\/gustavo-gomes.gif\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-18T13:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-22T17:51:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2023\/07\/06205122\/tipos-de-prospeccao.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/posts\/46916"}],"collection":[{"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/comments?post=46916"}],"version-history":[{"count":0,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/posts\/46916\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/media\/46917"}],"wp:attachment":[{"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/media?parent=46916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/categories?post=46916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/tags?post=46916"},{"taxonomy":"lista-de-leitura","embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/lista-de-leitura?post=46916"},{"taxonomy":"listas_de_leitura","embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/listas_de_leitura?post=46916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}