{"id":39710,"date":"2023-05-28T09:41:00","date_gmt":"2023-05-28T12:41:00","guid":{"rendered":"https:\/\/www.agendor.com.br\/blog\/?p=39710"},"modified":"2023-06-28T17:05:37","modified_gmt":"2023-06-28T20:05:37","slug":"csat","status":"publish","type":"post","link":"https:\/\/www.agendor.com.br\/blog\/csat\/","title":{"rendered":"O que \u00e9 CSAT? + Como funciona, como calcular e exemplos"},"content":{"rendered":"\n<p>O conceito de satisfa\u00e7\u00e3o do cliente \u00e9 complexo e formado por v\u00e1rios pilares. Um deles \u00e9 a pesquisa CSAT, o <em>Customer Satisfaction Score<\/em> \u2014 ou pontua\u00e7\u00e3o de satisfa\u00e7\u00e3o do cliente, em portugu\u00eas, que serve para identificar e resolver problemas no processo de atendimento ao consumidor.&nbsp;<\/p>\n\n\n\n<h3 class=\"titleKeyTakeaways\">Principais aprendizados deste artigo:<\/h3>\n\n\n\n<ul class=\"keyTakeaways\"><li>A pesquisa CSAT \u00e9 uma <a href=\"https:\/\/www.agendor.com.br\/blog\/metricas-de-satisfacao\/?cta=blog-principais-aprendizados\" target=\"_blank\" rel=\"noreferrer noopener\">m\u00e9trica de satisfa\u00e7\u00e3o dos clientes<\/a>. Ela avalia a efici\u00eancia do contato entre os consumidores e a empresa e d\u00e1 <em>insights<\/em> importantes para promover a melhora do atendimento.&nbsp;<\/li><li>Esse indicador deve ser utilizado continuamente e, normalmente, \u00e9 aplicado ap\u00f3s compras, <a href=\"https:\/\/www.agendor.com.br\/blog\/atendimento-ao-cliente\/?cta=blog-principais-aprendizados\" target=\"_blank\" rel=\"noreferrer noopener\">atendimento ao cliente<\/a>, entrega de produtos ou solicita\u00e7\u00f5es de suporte, e \u00e9 composto por perguntas diretas e respostas simples.<\/li><li>Esse n\u00e3o \u00e9 o \u00fanico <a href=\"https:\/\/www.agendor.com.br\/blog\/indicadores-de-satisfacao-do-cliente\/?cta=blog-principais-aprendizados\" target=\"_blank\" rel=\"noreferrer noopener\">indicador de satisfa\u00e7\u00e3o de clientes<\/a> existente, os outros s\u00e3o: NPS (Net Promoter Score), CES (Customer Effort Score) e CEV (Customer Emotional Value) e cada um deles possui objetivos diferentes.<\/li><li>Para aprender mais sobre m\u00e9tricas, baixe nosso e-book gratuito sobre <a href=\"https:\/\/materiais.agendor.com.br\/indicadores-vendas-marketing?cta=blog-principais-aprendizados\" target=\"_blank\" rel=\"noreferrer noopener\">indicadores de vendas e marketing<\/a> e confira quais KPIs voc\u00ea deve usar na sua empresa!<\/li><\/ul>\n\n\n\n<p>Essa avalia\u00e7\u00e3o \u00e9 crucial porque, muitas vezes, uma pequena falha no contato com o cliente pode colocar todo o seu trabalho a perder. Al\u00e9m disso, como saber o que sua empresa pode melhorar, se voc\u00ea n\u00e3o sabe onde est\u00e1 errando, certo?&nbsp;<\/p>\n\n\n\n<p>Por isso, preparamos um artigo completo para voc\u00ea. Nele, explicamos o que \u00e9 CSAT, como calcul\u00e1-lo e ainda como utilizar essa ferramenta para melhorar o seu relacionamento com os clientes. Confira!<\/p>\n\n\n\n<h2>Primeiramente, o que \u00e9 CSAT, afinal?<\/h2>\n\n\n\n<p>CSAT \u00e9 a sigla para <em>Customer Satisfaction Score<\/em>, em portugu\u00eas, Pontua\u00e7\u00e3o de Satisfa\u00e7\u00e3o do Cliente. O termo tamb\u00e9m \u00e9 conhecido como \u00edndice de Satisfa\u00e7\u00e3o do Cliente. Essa \u00e9 uma m\u00e9trica utilizada para saber a porcentagem de clientes satisfeitos com uma empresa, por meio de uma <a href=\"https:\/\/www.agendor.com.br\/blog\/importancia-pesquisa-de-satisfa\" target=\"_blank\" rel=\"noreferrer noopener\">pesquisa de satisfa\u00e7\u00e3o<\/a>.<\/p>\n\n\n\n<p>A avalia\u00e7\u00e3o CSAT facilita a descoberta de informa\u00e7\u00f5es sobre as etapas da jornada do cliente e a experi\u00eancia dele nos diferentes pontos de contato com a marca.&nbsp;<\/p>\n\n\n\n<p>Ela ainda pode ser utilizada para descobrir se o consumidor est\u00e1 satisfeito com o produto ou servi\u00e7o contratado, com o atendimento prestado, com a assist\u00eancia p\u00f3s-compra e muito mais.&nbsp;<\/p>\n\n\n\n<p>De qualquer forma, al\u00e9m de coletar o <a href=\"https:\/\/www.agendor.com.br\/blog\/feedbacks-de-clientes\/\" target=\"_blank\" rel=\"noreferrer noopener\">feedback dos usu\u00e1rios<\/a>, o CSAT evidencia processos que precisam de melhorias.\u00a0<\/p>\n\n\n\n<p>Por meio dos resultados, \u00e9 poss\u00edvel analisar e aprimorar a jornada de compra, o relacionamento entre marca e consumidor e a imagem que o cliente tem da empresa, por exemplo. Al\u00e9m disso, essa estrat\u00e9gia \u00e9 de f\u00e1cil implementa\u00e7\u00e3o e tem um custo baixo.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Compreendeu o que \u00e9 essa ferramenta? Ent\u00e3o continue conosco, pois explicamos como funciona o CSAT na pr\u00e1tica logo a seguir!<\/p>\n\n\n\n<h2>Como funciona o CSAT?<\/h2>\n\n\n\n<p>A avalia\u00e7\u00e3o CSAT funciona utilizando perguntas diretas e simples, que buscam saber a opini\u00e3o dos clientes sobre o atendimento. As respostas podem ser tanto em escala num\u00e9rica \u2014 geralmente de 0 a 10 \u2014 ou de percep\u00e7\u00e3o \u2014 satisfeito, regular, indiferente, pouco satisfeito ou ruim.&nbsp;<\/p>\n\n\n\n<p>No final, as respostas com notas acima da m\u00e9dia s\u00e3o separadas e comparadas com o total de avalia\u00e7\u00f5es. Pronto, o resultado \u00e9 o n\u00edvel de satisfa\u00e7\u00e3o dos clientes. F\u00e1cil, n\u00e3o \u00e9?<\/p>\n\n\n\n<h2>Quando usar o CSAT?<\/h2>\n\n\n\n<p>O CSAT \u00e9 uma m\u00e9trica que deve ser acompanhada de forma cont\u00ednua, para a empresa saber como est\u00e1 a experi\u00eancia do consumidor e seu <a href=\"https:\/\/www.agendor.com.br\/blog\/metricas-de-satisfacao\/\" target=\"_blank\" rel=\"noreferrer noopener\">grau de satisfa\u00e7\u00e3o<\/a>. Dito isso, a pesquisa CSAT pode ser implementada em diferentes pontos de contato, como ap\u00f3s:\u00a0<\/p>\n\n\n\n<ul><li>compras;<\/li><li>atendimentos (telef\u00f4nico, chat, presencial, etc.);<\/li><li>entrega de um produto;<\/li><li><a href=\"https:\/\/www.agendor.com.br\/blog\/como-fazer-pos-venda-o-que-e\/\" target=\"_blank\" rel=\"noreferrer noopener\">solicita\u00e7\u00e3o de suporte<\/a>, entre outros.<\/li><\/ul>\n\n\n\n<p>Vale lembrar que o <em>Customer Satisfaction Score<\/em> \u00e9 utilizado como uma ferramenta para ouvir a opini\u00e3o do consumidor. Por esse motivo, ela deve ser adaptada segundo o nicho da empresa e as etapas do processo comercial \u2014 <strong><em>veja mais no infogr\u00e1fico a seguir.<\/em><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img src=\"https:\/\/www.agendor.com.br\/blog\/wp-content\/uploads\/2017\/01\/14-As-7-etapas-do-processo-comercial.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<p>No mais, voc\u00ea tamb\u00e9m pode utilizar essa estrat\u00e9gia para fazer perguntas mais espec\u00edficas, como para descobrir se o prazo de entrega ou o valor do frete oferecido satisfaz os desejos dos consumidores.<\/p>\n\n\n\n<p>Continue com a leitura para ver um exemplo de CSAT para utilizar no seu neg\u00f3cio!<\/p>\n\n\n\n<h2>CSAT: exemplo de modelo de question\u00e1rio&nbsp;<\/h2>\n\n\n\n<p>Ap\u00f3s um contato com sua marca, o cliente pode responder a algumas perguntas simples, como estas que trouxemos abaixo.&nbsp;<\/p>\n\n\n\n<ul><li>Qual o seu n\u00edvel de satisfa\u00e7\u00e3o com o nosso produto?&nbsp;<\/li><li>Qual o seu n\u00edvel de satisfa\u00e7\u00e3o com a entrega realizada?<\/li><li>Qual o seu n\u00edvel de satisfa\u00e7\u00e3o com o atendimento que acabou de receber?&nbsp;<\/li><\/ul>\n\n\n\n<p>Para as respostas, basta escolher um dos modelos que indicamos \u2014 num\u00e9rico ou escala de percep\u00e7\u00e3o \u2014 e captar as respostas.&nbsp;<\/p>\n\n\n\n<p>Lembrando que esse \u00e9 apenas um exemplo. Portanto, o ideal \u00e9 us\u00e1-lo como base para criar sua pr\u00f3pria avalia\u00e7\u00e3o CSAT, perguntando o que faz realmente sentido para o seu modelo de neg\u00f3cio.&nbsp;<\/p>\n\n\n\n<h2>Como se calcula o CSAT?<\/h2>\n\n\n\n<p>O c\u00e1lculo CSAT depende inteiramente da escala escolhida para a avalia\u00e7\u00e3o. Se optar pela de percep\u00e7\u00e3o, basta identificar a quantidade de \u201cmuito satisfeito\u201d, \u201csatisfeito\u201d, \u201cexcelente\u201d ou \u201c\u00f3timo\u201d nas respostas e somar tudo.&nbsp;<\/p>\n\n\n\n<p>Caso tenha usado a escala num\u00e9rica, saiba que o c\u00e1lculo \u00e9 um pouco mais demorado. Para compreender melhor, trouxemos um exemplo pr\u00e1tico.&nbsp;<\/p>\n\n\n\n<p>Imagine que sua empresa realizou uma pesquisa de CSAT para descobrir a opini\u00e3o dos usu\u00e1rios de um novo aplicativo. Ao todo, 500 clientes enviaram suas considera\u00e7\u00f5es com as seguintes avalia\u00e7\u00f5es:<\/p>\n\n\n\n<ul><li>19 pessoas responderam 1, \u201cmuito insatisfeito\u201d;<\/li><li>29 pessoas responderam 2, \u201cinsatisfeito\u201d;<\/li><li>13 pessoas responderam 3, \u201cindiferente\u201d;<\/li><li>141 pessoas responderam 4, \u201csatisfeito\u201d;<\/li><li>298 pessoas responderam 5, \u201cmuito satisfeito\u201d.&nbsp;<\/li><\/ul>\n\n\n\n<p>Para chegar ao valor do CSAT, somamos o n\u00famero de respostas 4 e 5, referentes aos clientes que se consideram satisfeitos e muito satisfeitos:<\/p>\n\n\n\n<p>CSAT = 141 + 298&nbsp;<\/p>\n\n\n\n<p>CSAT = 439<\/p>\n\n\n\n<p>Em seguida, dividimos o valor de avalia\u00e7\u00f5es positivas pelo total de respostas obtidas:<\/p>\n\n\n\n<p>CSAT = 439 \/ 500<\/p>\n\n\n\n<p>CSAT = 0,878<\/p>\n\n\n\n<p>CSAT = 87,8%<\/p>\n\n\n\n<p>Assim, chegamos ao n\u00edvel de <em>Customer Satisfaction Score<\/em> que, nesse exemplo, \u00e9 de 87,8%.&nbsp;<\/p>\n\n\n\n<p>Compreendeu como se calcula o CSAT? Ent\u00e3o confira agora o que fazer para melhorar seus resultados!<\/p>\n\n\n\n<h2>Como melhorar o CSAT?<\/h2>\n\n\n\n<p>Para melhorar o CSAT, \u00e9 imprescind\u00edvel n\u00e3o apenas analisar os resultados das pesquisas, mas tamb\u00e9m investir em a\u00e7\u00f5es que aprimorem a experi\u00eancia do cliente. Em especial quando os resultados est\u00e3o abaixo do esperado que, por norma, \u00e9 de 70%.&nbsp;<\/p>\n\n\n\n<p>Caso sua avalia\u00e7\u00e3o fique nesse n\u00edvel ou abaixo, o ideal \u00e9:<\/p>\n\n\n\n<ul><li>analisar os <a href=\"https:\/\/www.agendor.com.br\/blog\/feedbacks-de-clientes\/\" target=\"_blank\" rel=\"noreferrer noopener\">feedbacks dos clientes<\/a> e colocar em pr\u00e1tica as mudan\u00e7as propostas;\u00a0<\/li><li>identificar as motiva\u00e7\u00f5es das avalia\u00e7\u00f5es negativas (atrasos, problemas no atendimento etc.);\u00a0<\/li><li>facilitar a pesquisa, com quest\u00f5es mais simples para reduzir o tempo necess\u00e1rio para as respostas;\u00a0<\/li><li>melhorar o relacionamento com os consumidores insatisfeitos.\u00a0<\/li><\/ul>\n\n\n\n<h2>Quais os outros indicadores de satisfa\u00e7\u00e3o do cliente?<\/h2>\n\n\n\n<p>Como falamos neste artigo, o CSAT mede exclusivamente a satisfa\u00e7\u00e3o do cliente. No entanto, ela n\u00e3o \u00e9 a \u00fanica ferramenta para identificar os sentimentos dos consumidores em rela\u00e7\u00e3o \u00e0 empresa. Algumas outras s\u00e3o o NPS, CES e CEV.&nbsp;<\/p>\n\n\n\n<p>Confira abaixo como cada um desses indicadores funcionam na pr\u00e1tica!<\/p>\n\n\n\n<h3>NPS<\/h3>\n\n\n\n<p>NPS ou <a href=\"https:\/\/www.agendor.com.br\/blog\/modelo-de-pesquisa-de-satisfacao\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Net Promoter Score<\/em><\/a> \u00e9 um indicador que vai al\u00e9m da satisfa\u00e7\u00e3o do cliente, \u00e9 uma m\u00e9trica de lealdade. Ele mostra se o consumidor indicaria os servi\u00e7os da companhia para outras pessoas.\u00a0<\/p>\n\n\n\n<p>Na abordagem tradicional, o NPS aplica a cl\u00e1ssica pergunta: \u201cem uma escala de 0 a 10, o quanto voc\u00ea recomendaria nossa empresa para um amigo?\u201d.&nbsp;<\/p>\n\n\n\n<p>Diferente do CSAT, o NPS n\u00e3o \u00e9 a pesquisa ideal para gerar <em>insights <\/em>de melhoria, uma vez que seu resultado aponta uma satisfa\u00e7\u00e3o ou insatisfa\u00e7\u00e3o geral com a empresa.<\/p>\n\n\n\n<p>Ou seja, ele n\u00e3o \u00e9 preciso o suficiente. Desse modo, n\u00e3o identifica pontos que precisam de maior aten\u00e7\u00e3o, apenas a imagem que os clientes t\u00eam da marca.<\/p>\n\n\n\n<p><strong><em>Para entender mais sobre essa m\u00e9trica, assista o v\u00eddeo abaixo:<\/em><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"NPS: A M\u00c9TRICA MAIS IMPORTANTE DE SATISFA\u00c7\u00c3O DO CLIENTE\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/i_a080BtSZw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3>CES&nbsp;<\/h3>\n\n\n\n<p>J\u00e1 o CES ou <em>Customer Effort Score<\/em> (\u00cdndice de Esfor\u00e7o do Cliente) \u00e9 o indicador que, como o nome j\u00e1 diz, mostra o esfor\u00e7o que os consumidores precisam fazer para usar os produtos ou servi\u00e7os de uma companhia.&nbsp;<\/p>\n\n\n\n<p>Ou seja, quanto tempo ele fica na linha a espera de um atendimento, quantas vezes ele precisa entrar em contato, quanto tempo demorou para ter sua solicita\u00e7\u00e3o atendida e assim por diante.&nbsp;<\/p>\n\n\n\n<p>Para essa metodologia, quanto menor o esfor\u00e7o do cliente para realizar uma a\u00e7\u00e3o, maior \u00e9 sua satisfa\u00e7\u00e3o e <a href=\"https:\/\/www.agendor.com.br\/blog\/o-que-e-experiencia-do-cliente\/\" target=\"_blank\" rel=\"noreferrer noopener\">melhor a experi\u00eancia<\/a>.<\/p>\n\n\n\n<h3>CEV<\/h3>\n\n\n\n<p>Por fim, o CEV \u00e9 o \u00edndice que mede o n\u00edvel de liga\u00e7\u00e3o emocional entre os clientes e a empresa. Diferente do NPS, CSAT ou CES, as informa\u00e7\u00f5es obtidas aqui n\u00e3o est\u00e3o diretamente relacionadas \u00e0 satisfa\u00e7\u00e3o, mas ao v\u00ednculo emocional entre o consumidor e a marca.<\/p>\n\n\n\n<p>Ou seja, o <em>Customer Emotional Value<\/em> identifica os sentimentos que a empresa gera nas pessoas e que podem influenciar diretamente a <a href=\"https:\/\/www.agendor.com.br\/blog\/etapas-do-processo-de-decisao-de-compra\/\" target=\"_blank\" rel=\"noreferrer noopener\">decis\u00e3o de compra<\/a>.\u00a0\u00a0<\/p>\n\n\n\n<p>Quando comparada com os outros indicadores da lista, essa \u00e9 uma m\u00e9trica bem mais recente. Contudo, ela \u00e9 uma excelente op\u00e7\u00e3o, porque ajuda a entender como se relacionar e apresentar os produtos da companhia para o p\u00fablico.&nbsp;<\/p>\n\n\n\n<h2>A busca pela satisfa\u00e7\u00e3o do cliente deve ser um trabalho constante<\/h2>\n\n\n\n<p>Todo mundo est\u00e1 cansado de saber que a satisfa\u00e7\u00e3o do cliente \u00e9 importante. Para voc\u00ea ter uma no\u00e7\u00e3o, uma <a href=\"https:\/\/www.liveworkstudio.com\/articles\/customer-experience-the-key-to-future-business\/\" target=\"_blank\" rel=\"noreferrer noopener\">pesquisa da Livework Studio<\/a> mostrou que 91% dos consumidores insatisfeitos n\u00e3o voltam a fazer neg\u00f3cios com a empresa.\u00a0<\/p>\n\n\n\n<p>Nesse caso, utilizar o m\u00e9todo de pesquisa CSAT permite entender como seu neg\u00f3cio pode melhorar. Por isso, n\u00e3o se esque\u00e7a de usar os dados obtidos com os question\u00e1rios para otimizar os seus processos.&nbsp;<\/p>\n\n\n\n<p>Com isso em m\u00e3os, invista em a\u00e7\u00f5es pr\u00e1ticas para aprimorar a rela\u00e7\u00e3o entre empresa e clientes e a imagem da sua marca no mercado. Afinal, o trabalho n\u00e3o deve parar, mesmo que voc\u00ea s\u00f3 receba feedbacks positivos.<\/p>\n\n\n\n<p><em>Para entender melhor como o feedback do seu consumidor pode melhorar at\u00e9 mesmo os resultados comerciais do seu neg\u00f3cio, baixe o <\/em><a href=\"https:\/\/materiais.agendor.com.br\/como-transformar-feedback-em-vendas\" target=\"_blank\" rel=\"noreferrer noopener\"><em>e-book gratuito<\/em><\/a><em> \u201cComo transformar o feedback dos clientes em vendas\u201d e descubra como criar valor para sua empresa por meio da opini\u00e3o de quem acredita na sua empresa.\u00a0<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O conceito de satisfa\u00e7\u00e3o do cliente \u00e9 complexo e formado por v\u00e1rios pilares. Um deles \u00e9 a pesquisa CSAT, o Customer Satisfaction Score \u2014 ou pontua\u00e7\u00e3o de satisfa\u00e7\u00e3o do cliente, em portugu\u00eas, que serve para identificar e resolver problemas no processo de atendimento ao consumidor.&nbsp; Principais aprendizados deste artigo: A pesquisa CSAT \u00e9 uma m\u00e9trica [&hellip;]<\/p>\n","protected":false},"author":48,"featured_media":39712,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[898],"tags":[713,794],"lista-de-leitura":[],"listas_de_leitura":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.6.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CSAT: o que \u00e9? Quando usar? Como calcular? Descubra agora<\/title>\n<meta name=\"description\" content=\"Voc\u00ea sabe o que \u00e9 CSAT? Entenda agora o que \u00e9, quando usar + exemplo pr\u00e1tico do c\u00e1lculo CSAT para medir a satisfa\u00e7\u00e3o do seu cliente.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.agendor.com.br\/blog\/csat\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CSAT: o que \u00e9? Quando usar? Como calcular? Descubra agora\" \/>\n<meta property=\"og:description\" content=\"Voc\u00ea sabe o que \u00e9 CSAT? Entenda agora o que \u00e9, quando usar + exemplo pr\u00e1tico do c\u00e1lculo CSAT para medir a satisfa\u00e7\u00e3o do seu cliente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.agendor.com.br\/blog\/csat\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Agendor\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/agendor\" \/>\n<meta property=\"article:author\" content=\"https:\/\/s3-sa-east-1.amazonaws.com\/agendor-materiais\/autores\/gustavo-gomes.gif\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-28T12:41:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-28T20:05:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2021\/09\/09093834\/CSAT.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/posts\/39710"}],"collection":[{"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/comments?post=39710"}],"version-history":[{"count":0,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/posts\/39710\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/media\/39712"}],"wp:attachment":[{"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/media?parent=39710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/categories?post=39710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/tags?post=39710"},{"taxonomy":"lista-de-leitura","embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/lista-de-leitura?post=39710"},{"taxonomy":"listas_de_leitura","embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/listas_de_leitura?post=39710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}