{"id":36504,"date":"2020-12-24T08:00:35","date_gmt":"2020-12-24T10:00:35","guid":{"rendered":"https:\/\/www.agendor.com.br\/blog\/?p=36504"},"modified":"2025-01-13T12:29:58","modified_gmt":"2025-01-13T15:29:58","slug":"ferramentas-planejamento-estrategico-comercial","status":"publish","type":"post","link":"https:\/\/www.agendor.com.br\/blog\/ferramentas-planejamento-estrategico-comercial\/","title":{"rendered":"5 metodologias + 5 ferramentas para o Planejamento Estrat\u00e9gico Comercial"},"content":{"rendered":"\n<p><span style=\"font-weight: 400;\">Voc\u00ea conhece as ferramentas para o Planejamento Estrat\u00e9gico Comercial? Elas s\u00e3o importantes para ajudar na organiza\u00e7\u00e3o de ideias e no acompanhamento dos projetos. <\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Afinal, para garantir seu funcionamento, \u00e9 necess\u00e1rio um estudo minucioso de diferentes \u00e1reas e quest\u00f5es relacionadas \u00e0s opera\u00e7\u00f5es de <\/span><a href=\"https:\/\/www.agendor.com.br\/blog\/marketing-e-vendas-de-uma-empresa\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">vendas e marketing<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Essa an\u00e1lise multidisciplinar \u00e9 uma tarefa desafiadora e, dentre tantos fatores a serem considerados, h\u00e1 grandes chances de a equipe do PEC se sentir sobrecarregada e acabar se perdendo.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Voc\u00ea tamb\u00e9m enfrenta essa dificuldade?<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Pensando em ajud\u00e1-lo nesse sentido, apresentamos a seguir 5 ferramentas para o Planejamento Estrat\u00e9gico Comercial e 5 metodologias que v\u00e3o orient\u00e1-lo na cria\u00e7\u00e3o, na aplica\u00e7\u00e3o e no monitoramento do PEC<\/span>.<\/p>\n\n\n\n<p><span style=\"font-weight: 400;\"><strong>Metodologias para criar, aplicar e monitorar o PEC:<\/strong><\/span><\/p>\n\n\n\n<ol><li><a href=\"#pdca\"><span style=\"font-weight: 400;\">Ciclo PDCA<\/span><\/a><\/li><li><span style=\"font-weight: 400;\"><a href=\"#5w2h\">5W2H<\/a><\/span><\/li><li><a href=\"#swot\"><span style=\"font-weight: 400;\">An\u00e1lise SWOT<\/span><\/a><\/li><li><a href=\"#business-model-canvas\"><span style=\"font-weight: 400;\">Business Model Canvas<\/span><\/a><\/li><li><span style=\"font-weight: 400;\"><a href=\"#matriz-bcg\">Matriz BCG<\/a><\/span><\/li><\/ol>\n\n\n\n<p><span style=\"font-weight: 400;\"><strong>Ferramentas para o Planejamento Estrat\u00e9gico Comercial:<\/strong><\/span><\/p>\n\n\n\n<ol><li><span style=\"font-weight: 400;\"><a href=\"#scopi\">Scopi<\/a><\/span><\/li><li><span style=\"font-weight: 400;\"><a href=\"#planest\">Planest<\/a><\/span><\/li><li><span style=\"font-weight: 400;\"><a href=\"#scoreplan\">Scoreplan<\/a><\/span><\/li><li><span style=\"font-weight: 400;\"><a href=\"#siteware\">Siteware<\/a><\/span><\/li><li><span style=\"font-weight: 400;\"><a href=\"#overtrak\">Overtrak<\/a><\/span><\/li><\/ol>\n\n\n\n<p><span style=\"font-weight: 400;\">Nossas dicas te ajudar\u00e3o a levar em considera\u00e7\u00e3o todos os elementos e as informa\u00e7\u00f5es relevantes para aumentar a efici\u00eancia e a precis\u00e3o do seu planejamento e de suas a\u00e7\u00f5es.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Confira!<\/span><\/p>\n\n\n\n<h2><span style=\"font-weight: 400;\"><strong>5 metodologias de an\u00e1lise para desenvolvimento e acompanhamento do PEC<\/strong><\/span><\/h2>\n\n\n\n<h3 id=\"pdca\"><span style=\"font-weight: 400;\"><strong>1. Ciclo PDCA<\/strong><\/span><\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img width=\"640\" height=\"635\" src=\"https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2020\/12\/17000250\/Ciclo-PDCA-ferramentas-planejamento-estrategico-640x635.png\" alt=\"Ciclo PDCA ferramentas planejamento estrat\u00e9gico\" class=\"wp-image-36505\" srcset=\"https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2020\/12\/17000250\/Ciclo-PDCA-ferramentas-planejamento-estrategico-640x635.png 640w, https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2020\/12\/17000250\/Ciclo-PDCA-ferramentas-planejamento-estrategico-768x762.png 768w, https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2020\/12\/17000250\/Ciclo-PDCA-ferramentas-planejamento-estrategico.png 981w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure><\/div>\n\n\n\n<p><b>O que \u00e9 o Ciclo PDCA:<\/b><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">O problema de muitos planejamentos \u00e9 que eles acabam \u201cmorrendo na praia\u201d, certo? Com o Ciclo PDCA, a tend\u00eancia \u00e9 que isso n\u00e3o aconte\u00e7a! Afinal, essa <\/span><a href=\"https:\/\/www.agendor.com.br\/blog\/o-que-e-gestao-estrategica\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">ferramenta de gest\u00e3o estrat\u00e9gica<\/span><\/a><span style=\"font-weight: 400;\"> prega que \u00e9 preciso avaliar constantemente os resultados e as a\u00e7\u00f5es estipuladas e fazer os ajustes necess\u00e1rios no plano para que tudo saia como esperado.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Plan, do, check, act\/adjust (ou, em tradu\u00e7\u00e3o livre, \u201cplanejar, fazer, analisar e agir\/ajustar\u201d) s\u00e3o os verbos que formam a sigla do <a href=\"https:\/\/www.nomus.com.br\/blog-industrial\/ciclo-pdca\/\" target=\"_blank\" rel=\"noopener\">ciclo PDCA<\/a>.<\/span><\/p>\n\n\n\n<p><b>Como funciona:<\/b><\/p>\n\n\n\n<ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Os objetivos a serem alcan\u00e7ados\/problemas a serem resolvidos, as t\u00e1ticas necess\u00e1rias para o alcance das metas, os respons\u00e1veis pelas a\u00e7\u00f5es e os prazos de implementa\u00e7\u00e3o s\u00e3o definidos na fase \u201cplanejar\u201d.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">A etapa \u201cfazer\u201d \u00e9, como o nome diz, o momento de realizar o que foi planejado.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">O est\u00e1gio de an\u00e1lise pede a avalia\u00e7\u00e3o dos resultados obtidos com as t\u00e1ticas e a\u00e7\u00f5es realizadas.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Por fim, vem o momento de agir em cima dos resultados obtidos, ajustar o que for necess\u00e1rio no planejamento inicial e come\u00e7ar o PDCA novamente. Sim, porque o Ciclo PDCA n\u00e3o \u00e9 algo que se faz uma vez e abandona. Ao fim de cada \u201cvolta\u201d, inicia-se uma nova.<\/span><\/li><\/ul>\n\n\n\n<p><b>Por que o PDCA \u00e9 uma das ferramentas para o planejamento estrat\u00e9gico comercial?<\/b><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Voc\u00ea pode utilizar o ciclo PDCA periodicamente (uma vez por m\u00eas ou a cada trimestre, por exemplo) para manter o PEC em dia, garantindo que ele continue em andamento e que esteja efetivamente funcionando.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Caso algo n\u00e3o esteja trazendo o resultado esperado, h\u00e1 tempo para fazer as adapta\u00e7\u00f5es necess\u00e1rias.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Uma dica interessante \u00e9 fazer o PDCA para objetivos e tarefas espec\u00edficas do PEC, distribuindo a responsabilidade entre diferentes profissionais e \u00e1reas.<\/span><\/p>\n\n\n\n<p><em><strong>Na pr\u00e1tica: Confira <a href=\"http:\/\/bit.ly\/pdcavm\" target=\"_blank\" rel=\"noreferrer noopener\">aqui<\/a> um modelo de planilha que pode ajud\u00e1-lo a colocar o ciclo PDCA em pr\u00e1tica!&nbsp;<\/strong><\/em><\/p>\n\n\n\n<h3 id=\"5w2h\"><span style=\"font-weight: 400;\"><strong>2. 5W2H<\/strong><\/span><\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img width=\"640\" height=\"198\" src=\"https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2020\/12\/17000425\/salestech-5W2H-640x198.png\" alt=\"salestech-5W2H\" class=\"wp-image-36507\" srcset=\"https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2020\/12\/17000425\/salestech-5W2H-640x198.png 640w, https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2020\/12\/17000425\/salestech-5W2H-768x237.png 768w, https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2020\/12\/17000425\/salestech-5W2H.png 773w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure><\/div>\n\n\n\n<p><span style=\"font-weight: 400;\"><\/span><\/p>\n\n\n\n<p><b>O que \u00e9 5W2H<\/b><span style=\"font-weight: 400;\">:<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">O <\/span><a href=\"https:\/\/www.agendor.com.br\/blog\/plano-de-acao-5w2h\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">plano de a\u00e7\u00e3o 5W2H <\/span><\/a><span style=\"font-weight: 400;\">\u00e9 uma esp\u00e9cie de checklist de apoio para o desenvolvimento de planejamentos e projetos. Essa ferramenta ajuda a guiar as informa\u00e7\u00f5es e especifica\u00e7\u00f5es necess\u00e1rias para que o projeto seja executado da melhor maneira.<\/span><\/p>\n\n\n\n<p><b>Como funciona:<\/b><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">A sigla que forma o nome desse m\u00e9todo diz respeito a sete aspectos fundamentais para a cria\u00e7\u00e3o de um planejamento realmente eficiente: cinco fatores que come\u00e7am com a letra W (em ingl\u00eas) e dois que come\u00e7am com a letra H (tamb\u00e9m em ingl\u00eas) \u2013 da\u00ed o nome 5W2H.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">S\u00e3o eles:<\/span><\/p>\n\n\n\n<ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">What (o qu\u00ea) \u2013 do que se trata o projeto.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Why (por qu\u00ea) \u2013 qual \u00e9 o objetivo dele.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Where (onde) \u2013 onde ele vai ser realizado.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Who (quem) \u2013 quem ser\u00e3o os envolvidos nele.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">When (quando) \u2013 quais s\u00e3o os prazos de execu\u00e7\u00e3o.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">How (como) \u2013 o que ser\u00e1 feito para coloc\u00e1-lo em pr\u00e1tica.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">How much (quanto) \u2013 qual ser\u00e1 o or\u00e7amento.<\/span><\/li><\/ul>\n\n\n\n<p><b>Como pode ajudar no desenvolvimento do PEC:<\/b><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">As sete perguntas do 5W2H o ajudar\u00e3o a montar um mapa de necessidades e atividades que precisam ser realizadas para que os objetivos do seu <\/span><a href=\"https:\/\/www.agendor.com.br\/blog\/planejamento-estrategico-comercial\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">Planejamento Estrat\u00e9gico Comercial<\/span><\/a><span style=\"font-weight: 400;\"> possam ser efetivamente alcan\u00e7ados. Esse direcionamento ajuda a deixar claro quais s\u00e3o as atividades e responsabilidades de cada um.<\/span><\/p>\n\n\n\n<p><strong><em>Na pr\u00e1tica: Confira um modelo de <a href=\"https:\/\/www.agendor.com.br\/blog\/planilha-5w2h\/\" target=\"_blank\" rel=\"noreferrer noopener\">planilha 5w2h<\/a> que pode ajud\u00e1-lo a colocar a metodologia em pr\u00e1tica<\/em><\/strong><\/p>\n\n\n\n<h3 id=\"swot\"><span style=\"font-weight: 400;\"><strong>3. An\u00e1lise SWOT<\/strong><\/span><\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img width=\"640\" height=\"392\" src=\"https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2020\/12\/17000524\/SWOT-ferramentas-para-o-planejamento-estrategico-comercial-640x392.png\" alt=\"SWOT - ferramentas para o planejamento estrat\u00e9gico comercial\" class=\"wp-image-36508\" srcset=\"https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2020\/12\/17000524\/SWOT-ferramentas-para-o-planejamento-estrategico-comercial-640x392.png 640w, https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2020\/12\/17000524\/SWOT-ferramentas-para-o-planejamento-estrategico-comercial-768x470.png 768w, https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2020\/12\/17000524\/SWOT-ferramentas-para-o-planejamento-estrategico-comercial.png 944w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure><\/div>\n\n\n\n<p><b>O que \u00e9 An\u00e1lise SWOT:<\/b><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">A <\/span><a href=\"https:\/\/www.agendor.com.br\/blog\/analise-swot-de-uma-empresa\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">an\u00e1lise SWOT de uma empresa<\/span><\/a><span style=\"font-weight: 400;\"> \u00e9 uma ferramenta muito \u00fatil para identificar tanto as oportunidades quanto os perigos para sua empresa.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Essa metodologia analisa fatores internos da organiza\u00e7\u00e3o, combinando com movimenta\u00e7\u00f5es externas relacionadas ao mercado (concorr\u00eancia, setor, economia, tend\u00eancias etc.). A partir desse estudo, \u00e9 poss\u00edvel prever e identificar poss\u00edveis cen\u00e1rios positivos e negativos \u2013 e agir a partir disso.<\/span><\/p>\n\n\n\n<p><b>Como funciona:<\/b><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">A sigla SWOT diz respeito \u00e0s palavras inglesas<\/span><i><span style=\"font-weight: 400;\"> strengths, weaknesses, opportunities e threats<\/span><\/i><span style=\"font-weight: 400;\">. Em uma tradu\u00e7\u00e3o literal: for\u00e7as, fraquezas, oportunidade e amea\u00e7as.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">A ideia da <\/span><a href=\"https:\/\/www.agendor.com.br\/blog\/definicao-de-analise-swot\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">an\u00e1lise SWOT<\/span><\/a><span style=\"font-weight: 400;\"> \u00e9 estudar cada uma dessas quest\u00f5es de maneira isolada e tamb\u00e9m combinando os diferentes fatores para chegar a um diagn\u00f3stico sobre as chances da empresa.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Por exemplo: suponhamos que um dos pontos fortes da empresa seja a entrega r\u00e1pida e a consultoria personalizada. Entretanto, ela possui a fraqueza de ter um pre\u00e7o acima do mercado. Neste caso, \u00e9 poss\u00edvel entender que \u00e9 preciso apresentar melhor os benef\u00edcios e diferenciais (como a entrega mais veloz e o atendimento exclusivo) que justificam o valor acima da m\u00e9dia.<\/span><\/p>\n\n\n\n<p><b>Por que a an\u00e1lise SWOT \u00e9 uma das aliadas no planejamento estrat\u00e9gico de vendas:<\/b><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Esse estudo pode ser especialmente \u00fatil no desenvolvimento do PEC porque aponta quais s\u00e3o as reais necessidades e possibilidades da empresa no mercado.&nbsp;<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Ao fazer esse diagn\u00f3stico e identificar poss\u00edveis cen\u00e1rios e possibilidades de crescimento, \u00e9 poss\u00edvel direcionar o planejamento comercial de maneira mais estrat\u00e9gica.<\/span><\/p>\n\n\n\n<p><strong><em><strong>Na pr\u00e1tica:<\/strong> Confira um <a href=\"https:\/\/www.agendor.com.br\/blog\/wp-admin\/blank\" target=\"_blank\" rel=\"noreferrer noopener\">modelo de planilha<\/a> que pode ajud\u00e1-lo a fazer a an\u00e1lise SWOT.<\/em><\/strong><\/p>\n\n\n\n<h3 id=\"business-model-canvas\"><span style=\"font-weight: 400;\"><strong>4. Business Model Canvas<\/strong><\/span><\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img width=\"640\" height=\"382\" src=\"https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2020\/12\/17000611\/canvas-ferramentas-para-o-planejamento-estrategico-comercial-640x382.jpg\" alt=\"canvas ferramentas para o planejamento estrat\u00e9gico comercial\" class=\"wp-image-36509\" srcset=\"https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2020\/12\/17000611\/canvas-ferramentas-para-o-planejamento-estrategico-comercial-640x382.jpg 640w, https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2020\/12\/17000611\/canvas-ferramentas-para-o-planejamento-estrategico-comercial-768x459.jpg 768w, https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2020\/12\/17000611\/canvas-ferramentas-para-o-planejamento-estrategico-comercial.jpg 951w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure><\/div>\n\n\n\n<p><span style=\"font-weight: 400;\"><\/span><\/p>\n\n\n\n<p><b>O que \u00e9 o Business Model Canvas:<\/b><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Canvas \u00e9 uma ferramenta utilizada para montar modelos de neg\u00f3cios. A partir de um Canvas, cria-se um gr\u00e1fico com os principais fatores que envolvem a cria\u00e7\u00e3o de uma empresa\/de um projeto ou de uma estrat\u00e9gia.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Essa metodologia determina as a\u00e7\u00f5es e os objetivos relacionados a esses pontos-chave, fornecendo uma vis\u00e3o ampla sobre diferentes \u00e1reas e quest\u00f5es envolvidas na organiza\u00e7\u00e3o\/projeto.<\/span><\/p>\n\n\n\n<p><b>Como funciona:<\/b><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">O foco do desenvolvimento do Canvas \u00e9 a cria\u00e7\u00e3o da proposta de valor \u2013 e o desenvolvimento de t\u00e1ticas e a\u00e7\u00f5es a partir disso.&nbsp;<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Com essa ferramenta, \u00e9 poss\u00edvel desenvolver um mapa visual do planejamento\/estrat\u00e9gia em quest\u00e3o, levando em conta 9 \u00e1reas que respondem a 4 perguntas fundamentais. S\u00e3o elas:<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Como?<\/span><\/p>\n\n\n\n<ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Parcerias-chave.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Atividades-chave.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Recursos-chave.<\/span><\/li><\/ul>\n\n\n\n<p><span style=\"font-weight: 400;\">O qu\u00ea?<\/span><\/p>\n\n\n\n<ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Proposta de valor.<\/span><\/li><\/ul>\n\n\n\n<p><span style=\"font-weight: 400;\">Para quem?<\/span><\/p>\n\n\n\n<ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Relacionamento com os clientes.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Canais.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Segmentos de clientes.<\/span><\/li><\/ul>\n\n\n\n<p><span style=\"font-weight: 400;\">Quanto?<\/span><\/p>\n\n\n\n<ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Estruturas de custo.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Fontes de receita.<\/span><\/li><\/ul>\n\n\n\n<p><b>Como pode ajudar no desenvolvimento do PEC:<\/b><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Essa metodologia geralmente \u00e9 utilizada para a cria\u00e7\u00e3o de um modelo de neg\u00f3cios de uma nova empresa. No entanto, tamb\u00e9m pode ser muito \u00fatil na cria\u00e7\u00e3o do PEC.&nbsp;<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Afinal, ao determinar ou revisitar os <\/span><a href=\"https:\/\/www.agendor.com.br\/blog\/gestao-baseada-em-valores-equipe-vendas\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">valores fundamentais para a empresa<\/span><\/a><span style=\"font-weight: 400;\"> e o que ela deseja oferecer aos clientes, ser\u00e1 muito mais f\u00e1cil entender quais s\u00e3o as atividades e os recursos necess\u00e1rios para aprimorar os resultados comerciais.<\/span><\/p>\n\n\n\n<p><b><em><strong>Na pr\u00e1tica:<\/strong> Confira um <a href=\"http:\/\/bit.ly\/canvas-vm\" target=\"_blank\" rel=\"noreferrer noopener\">modelo de planilha<\/a> que pode ajud\u00e1-lo a utilizar o Canvas na cria\u00e7\u00e3o do PEC!&nbsp;<\/em><\/b><\/p>\n\n\n\n<h3 id=\"matriz-bcg\"><span style=\"font-weight: 400;\"><strong>5. Matriz BCG<\/strong><\/span><\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img width=\"640\" height=\"504\" src=\"https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2020\/12\/17000649\/matriz-bcg-ferramentas-pec-640x504.png\" alt=\"matriz bcg - ferramentas pec\" class=\"wp-image-36510\" srcset=\"https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2020\/12\/17000649\/matriz-bcg-ferramentas-pec-640x504.png 640w, https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2020\/12\/17000649\/matriz-bcg-ferramentas-pec-768x604.png 768w, https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2020\/12\/17000649\/matriz-bcg-ferramentas-pec.png 938w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure><\/div>\n\n\n\n<p><b>O que \u00e9 Matriz BCG:&nbsp;<\/b><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Essa metodologia foi desenvolvida pela consultoria Boston Consulting Group \u2013 da\u00ed a sigla do nome, <\/span><a href=\"https:\/\/www.agendor.com.br\/blog\/o-que-e-bcg\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">BCG<\/span><\/a><span style=\"font-weight: 400;\">. O objetivo \u00e9 realizar uma an\u00e1lise do portf\u00f3lio de produtos\/servi\u00e7os da empresa, avaliando seus ciclos de vida e sua participa\u00e7\u00e3o no mercado. A matriz BCG ajuda a direcionar melhor os investimentos em a\u00e7\u00f5es de marketing, de acordo com a performance de cada produto\/servi\u00e7o.<\/span><\/p>\n\n\n\n<p><b>Como funciona:<\/b><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">A ferramenta divide os produtos\/servi\u00e7os em diferentes categorias de ciclo de vida:<\/span><\/p>\n\n\n\n<ul><li><b>Estrelas:<\/b><span style=\"font-weight: 400;\"> produtos\/servi\u00e7os que possuem alto n\u00edvel de crescimento e geram um grande retorno. Exigem alto investimento, mas t\u00eam grande potencial de aumentar cada vez mais a participa\u00e7\u00e3o de mercado e o faturamento.<\/span><\/li><li><b>Pontos de interroga\u00e7\u00e3o: <\/b><span style=\"font-weight: 400;\">s\u00e3o itens ainda incertos em rela\u00e7\u00e3o a seu sucesso. Por exemplo: produtos rec\u00e9m-lan\u00e7ados ou inovadores. Exigem alto investimento para promo\u00e7\u00e3o e ainda n\u00e3o geram tanta receita quanto os itens \u201cestrela\u201d.<\/span><\/li><li><b>Vacas leiteiras:<\/b><span style=\"font-weight: 400;\"> s\u00e3o a evolu\u00e7\u00e3o dos produtos estrela. \u00c9 quando, depois do alto investimento inicial na promo\u00e7\u00e3o, o produto\/servi\u00e7o j\u00e1 se estabeleceu no mercado e continua gerando grande receita, mas com menos necessidade de investimento.<\/span><\/li><li><b>Abacaxi:<\/b><span style=\"font-weight: 400;\"> s\u00e3o produtos\/servi\u00e7os que j\u00e1 n\u00e3o geram bons resultados. Possuem baixo retorno e baixa participa\u00e7\u00e3o no mercado \u2013 sinalizam o poss\u00edvel fim do ciclo de vida do produto (ainda que, em alguns casos, seja poss\u00edvel recuper\u00e1-los).<\/span><\/li><\/ul>\n\n\n\n<p><span style=\"font-weight: 400;\">Depois de encaixar seus produtos\/servi\u00e7os em cada uma dessas categorias, \u00e9 preciso definir os pr\u00f3ximos passos em rela\u00e7\u00e3o a eles para alocar os recursos nas melhores oportunidades para a empresa.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Levando em considera\u00e7\u00e3o o n\u00edvel de crescimento e o retorno financeiro gerado pelos produtos, a matriz BCG indica as seguintes pr\u00e1ticas:<\/span><\/p>\n\n\n\n<ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Baixo crescimento e alta participa\u00e7\u00e3o no mercado<\/b><span style=\"font-weight: 400;\"> \u2013 empresas devem aproveitar o lucro das \u201cvacas leiteiras\u201d para investir em outros produtos que est\u00e3o na fase inicial do ciclo de vida.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Alto crescimento e alta participa\u00e7\u00e3o no mercado<\/b><span style=\"font-weight: 400;\"> \u2013 empresas devem investir pesado nas \u201cestrelas\u201d, pois elas possuem grande potencial futuro.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Alto crescimento e baixa participa\u00e7\u00e3o no mercado<\/b><span style=\"font-weight: 400;\"> \u2013 empresas precisam avaliar a situa\u00e7\u00e3o dos \u201cpontos de interroga\u00e7\u00e3o\u201d para decidir se investem mais neles ou os eliminam do portf\u00f3lio.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Baixo crescimento e baixa participa\u00e7\u00e3o no mercado<\/b><span style=\"font-weight: 400;\"> \u2013 empresas devem liquidar ou reposicionar esses \u201cabacaxis\u201d.<\/span><\/li><\/ul>\n\n\n\n<p><b>Como pode ajudar no desenvolvimento do PEC:<\/b><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Essa an\u00e1lise vai ajud\u00e1-lo a entender para quais produtos\/servi\u00e7os espec\u00edficos as a\u00e7\u00f5es do PEC devem estar direcionadas.&nbsp;<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Se h\u00e1 um cen\u00e1rio de alto crescimento e baixo retorno, por exemplo, o <\/span><a href=\"https:\/\/www.agendor.com.br\/blog\/planejamento-de-vendas-2021\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">planejamento de vendas<\/span><\/a><span style=\"font-weight: 400;\"> pode girar em torno de promover determinados produtos com alto potencial de lucro e participa\u00e7\u00e3o de mercado.<\/span><\/p>\n\n\n\n<p><b><em><strong>Na pr\u00e1tica:<\/strong> Confira um <a href=\"http:\/\/bit.ly\/bcg-vm\" target=\"_blank\" rel=\"noreferrer noopener\">modelo de planilha <\/a>que pode ajud\u00e1-lo a colocar a matriz BCG em pr\u00e1tica.<\/em><\/b><\/p>\n\n\n\n<h2><span style=\"font-weight: 400;\"><strong>5 ferramentas para o Planejamento Estrat\u00e9gico Comercial<\/strong><\/span><\/h2>\n\n\n\n<p><span style=\"font-weight: 400;\">As planilhas e os modelos que compartilhamos at\u00e9 aqui podem ser muito \u00fateis para dar os primeiros passos na utiliza\u00e7\u00e3o dessas metodologias no desenvolvimento do PEC. Contudo, se voc\u00ea quer <\/span><a href=\"https:\/\/www.agendor.com.br\/blog\/baixe-nosso-novo-ebook-sobre-automatizacao-de-processos\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">automatizar esses processos<\/span><\/a><span style=\"font-weight: 400;\"> e facilitar a implementa\u00e7\u00e3o dessas an\u00e1lises, pode contar com a ajuda da tecnologia.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Os sistemas que apresentamos a seguir ajudam a otimizar o desenvolvimento das metodologias citadas anteriormente. Al\u00e9m disso, oferecem outras funcionalidades importantes para o desenvolvimento e acompanhamento do planejamento de a\u00e7\u00f5es da \u00e1rea comercial. Conhe\u00e7a-os, analise suas funcionalidades e descubra quais podem ser \u00fateis para a sua empresa.<\/span><\/p>\n\n\n\n<h3 id=\"scopi\"><span style=\"font-weight: 400;\"><strong>1. Scopi<\/strong><\/span><\/h3>\n\n\n\n<p><span style=\"font-weight: 400;\">Funcionalidades do <\/span><a href=\"http:\/\/scopi.com.br\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">Scopi<\/span><\/a><span style=\"font-weight: 400;\">:<\/span><\/p>\n\n\n\n<ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">desenho do modelo de neg\u00f3cio por meio do Canvas;<\/span><\/li><li><span style=\"font-weight: 400;\">gest\u00e3o de projetos e processos;<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">diagn\u00f3sticos Estrat\u00e9gicos (SWOT);<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">defini\u00e7\u00e3o de objetivos estrat\u00e9gicos;<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">gest\u00e3o de indicadores;<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">gest\u00e3o de tarefas.<\/span><\/li><\/ul>\n\n\n\n<p><span style=\"font-weight: 400;\">Pre\u00e7os variam dependendo da quantidade de usu\u00e1rios<\/span><\/p>\n\n\n\n<h3 id=\"planest\"><span style=\"font-weight: 400;\"><strong>2. Planest<\/strong><\/span><\/h3>\n\n\n\n<p><span style=\"font-weight: 400;\">Funcionalidades do <\/span><a href=\"http:\/\/planest.com.br\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">Planest<\/span><\/a><span style=\"font-weight: 400;\">:<\/span><\/p>\n\n\n\n<ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">desenvolvimento do plano de neg\u00f3cios;<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">an\u00e1lise de cen\u00e1rios (SWOT);<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">gest\u00e3o de indicadores;<\/span><\/li><li><span style=\"font-weight: 400;\">diagn\u00f3stico de mercado;<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">an\u00e1lise de desempenho;<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">plano de a\u00e7\u00f5es;<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Monitoramento.<\/span><\/li><\/ul>\n\n\n\n<p><span style=\"font-weight: 400;\">H\u00e1 um plano gratuito, para quem est\u00e1 come\u00e7ando; uma vers\u00e3o para pequenas e m\u00e9dias empresas (que custa R$199 por m\u00eas) e outra para consultoria\/revenda (R$99 por m\u00eas).<\/span><\/p>\n\n\n\n<h3 id=\"scoreplan\"><span style=\"font-weight: 400;\"><strong>3. Scoreplan<\/strong><\/span><\/h3>\n\n\n\n<p>Softwares da <a href=\"http:\/\/scoreplan.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Scoreplan<\/a>:&nbsp;&nbsp;<\/p>\n\n\n\n<ul><li>Planejamento Estrat\u00e9gico;<\/li><li>Planejamento Or\u00e7ament\u00e1rio;<\/li><li>Gest\u00e3o de Pessoas;<\/li><li>Gest\u00e3o da Qualidade;<\/li><li>Gest\u00e3o de Projetos;<\/li><li>GED;<\/li><li>OKRs;<\/li><li>BSC;<\/li><li>Planos de A\u00e7\u00e3o;<\/li><li>Indicadores;<\/li><li>Ocorr\u00eancias;<\/li><li>Gest\u00e3o de Riscos;<\/li><li>Auditorias.<\/li><\/ul>\n\n\n\n<p>A Scoreplan oferece 13 softwares com mais de 600 funcionalidades em uma \u00fanica plataforma. Al\u00e9m disso, ela conta com sua pr\u00f3pria intelig\u00eancia artificial para auxiliar seus clientes, a <a href=\"https:\/\/materiais.scoreplan.com.br\/sage-ia\" target=\"_blank\" rel=\"noreferrer noopener\">Sage IA<\/a>.<\/p>\n\n\n\n<h3 id=\"siteware\"><span style=\"font-weight: 400;\"><strong>4. Siteware<\/strong><\/span><\/h3>\n\n\n\n<p><span style=\"font-weight: 400;\">Funcionalidades do <\/span><a href=\"http:\/\/siteware.com.br\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">Siteware<\/span><\/a><span style=\"font-weight: 400;\">:<\/span><\/p>\n\n\n\n<ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">re\u00fane indicadores estrat\u00e9gicos, t\u00e1ticos e operacionais, integrando com outros sistemas ou <\/span><a href=\"https:\/\/www.agendor.com.br\/blog\/erp-o-que-e-e-para-que-serve\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">ERPs<\/span><\/a><span style=\"font-weight: 400;\"> utilizados pela empresa;<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">realiza a identifica\u00e7\u00e3o de solu\u00e7\u00e3o de problemas e a cria\u00e7\u00e3o do plano de a\u00e7\u00f5es (PDCA; 5W2H);<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">monitora o desempenho individual dos colaboradores.<\/span><\/li><\/ul>\n\n\n\n<p><span style=\"font-weight: 400;\">Para conhecer os pre\u00e7os e planos, \u00e9 preciso solicitar uma demonstra\u00e7\u00e3o.<\/span><\/p>\n\n\n\n<h3 id=\"overtrak\"><span style=\"font-weight: 400;\"><strong>5. Overtrak<\/strong><\/span><\/h3>\n\n\n\n<p><span style=\"font-weight: 400;\">Funcionalidades do <\/span><a href=\"http:\/\/overtrak.com.br\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">Overtrak<\/span><\/a><span style=\"font-weight: 400;\">:<\/span><\/p>\n\n\n\n<ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">listagem de problemas\/objetivos e desenvolvimento do plano de a\u00e7\u00f5es (PDCA; 5W2H).<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">gest\u00e3o das tarefas e prazos.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">monitoramento sobre a evolu\u00e7\u00e3o das atividades e metas.<\/span><\/li><\/ul>\n\n\n\n<p><span style=\"font-weight: 400;\">\u00c9 poss\u00edvel fazer um teste gratuito. Depois, voc\u00ea precisar\u00e1 migrar para o plano Premium, que \u00e9 pr\u00e9-pago.<\/span><\/p>\n\n\n\n<h2><span style=\"font-weight: 400;\"><strong>Aproveite nossas dicas para fazer um bom planejamento estrat\u00e9gico comercial&nbsp;<\/strong><\/span><\/h2>\n\n\n\n<p><span style=\"font-weight: 400;\">Ap\u00f3s a leitura deste artigo, voc\u00ea ter\u00e1 em m\u00e3os todas as metodologias e ferramentas para o planejamento estrat\u00e9gico comercial. Elas ajudar\u00e3o a gerir metas e indicadores com assertividade. <\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, permitem acompanhar o desempenho das equipes e fazer ajustes de percurso de forma pontual e direcionada.&nbsp;<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Aproveite o fim desta leitura para planejar suas a\u00e7\u00f5es para o pr\u00f3ximo ano. Se ainda n\u00e3o sabe por onde come\u00e7ar, n\u00e3o se preocupe. O Agendor disponibilizou, para acesso gratuito, o webinar \u201cPlanejamento Estrat\u00e9gico Comercial para 2025\u201d. <\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Basta <a href=\"https:\/\/materiais.agendor.com.br\/webinar-planejamento-comercial-2025\" target=\"_blank\" rel=\"noreferrer noopener\">preencher o formul\u00e1rio<\/a> para acessar o link e descobrir as novas tend\u00eancias e pr\u00e1ticas fundamentais para gerir seu neg\u00f3cio.&nbsp;<\/span><\/p>\n\n\n\n<p><em><a href=\"https:\/\/premium.vendamais.com.br\/5-metodologias-e-5-ferramentas-digitais-para-apoiar-a-criacao-e-o-monitoramento-do-pec\/\" target=\"_blank\" rel=\"noreferrer noopener\">Artigo cedido pela Revista VendaMais. Todos os direitos reservados.*<\/a><\/em><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\"><em>*Otimizado pela equipe Agendor em dezembro de 2020.<\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea conhece as ferramentas para o Planejamento Estrat\u00e9gico Comercial? Elas s\u00e3o importantes para ajudar na organiza\u00e7\u00e3o de ideias e no acompanhamento dos projetos. Afinal, para garantir seu funcionamento, \u00e9 necess\u00e1rio um estudo minucioso de diferentes \u00e1reas e quest\u00f5es relacionadas \u00e0s opera\u00e7\u00f5es de vendas e marketing. Essa an\u00e1lise multidisciplinar \u00e9 uma tarefa desafiadora e, dentre tantos [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":36512,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[883],"tags":[795],"lista-de-leitura":[],"listas_de_leitura":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.6.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>5 m\u00e9todos + 5 ferramentas para o Planejamento Estrat\u00e9gico Comercial<\/title>\n<meta name=\"description\" content=\"Conhe\u00e7a 5 metodologias e 5 ferramentas para o seu Planejamento Estrat\u00e9gico Comercial. Organize processos e mensure resultados com precis\u00e3o!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.agendor.com.br\/blog\/ferramentas-planejamento-estrategico-comercial\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 m\u00e9todos + 5 ferramentas para o Planejamento Estrat\u00e9gico Comercial\" \/>\n<meta property=\"og:description\" content=\"Conhe\u00e7a 5 metodologias e 5 ferramentas para o seu Planejamento Estrat\u00e9gico Comercial. Organize processos e mensure resultados com precis\u00e3o!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.agendor.com.br\/blog\/ferramentas-planejamento-estrategico-comercial\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Agendor\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/agendor\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-24T10:00:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-13T15:29:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2020\/12\/17001721\/ferramentas-para-o-planejamento-estrategico-comercial.png\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/posts\/36504"}],"collection":[{"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/comments?post=36504"}],"version-history":[{"count":0,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/posts\/36504\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/media\/36512"}],"wp:attachment":[{"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/media?parent=36504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/categories?post=36504"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/tags?post=36504"},{"taxonomy":"lista-de-leitura","embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/lista-de-leitura?post=36504"},{"taxonomy":"listas_de_leitura","embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/listas_de_leitura?post=36504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}