{"id":33797,"date":"2020-02-13T09:00:11","date_gmt":"2020-02-13T11:00:11","guid":{"rendered":"https:\/\/www.agendor.com.br\/blog\/?p=33797"},"modified":"2020-02-18T15:40:23","modified_gmt":"2020-02-18T18:40:23","slug":"ideias-fidelizar-clientes","status":"publish","type":"post","link":"https:\/\/www.agendor.com.br\/blog\/ideias-fidelizar-clientes\/","title":{"rendered":"25 ideias para aumentar a lealdade e fidelizar clientes"},"content":{"rendered":"<p><em>Artigo cedido pela Revista Venda Mais. Todos os direitos reservados.<\/em><\/p>\n<p>Fideliza\u00e7\u00e3o de clientes \u00e9 sempre um assunto \u201cquente\u201d nos meus workshops e cursos, e uma coisa fica evidente logo de cara: fideliza\u00e7\u00e3o (ou lealdade) de clientes \u00e9 mais ou menos como sexo entre adolescentes \u2013 muita gente fala mais do que faz, poucos fazem de verdade e os que fazem ainda podem melhorar muito.<\/p>\n<p>Todo mundo diz que fidelizar \u00e9 importante, mas, na pr\u00e1tica, o foco \u00e9 todo em\u00a0<strong>prospec\u00e7\u00e3o<\/strong>\u00a0ou em\u00a0<strong>vender mais<\/strong>\u00a0para os atuais clientes.<\/p>\n<p>As duas coisas s\u00e3o \u00f3timas, necess\u00e1rias, t\u00eam muito espa\u00e7o para crescimento, por\u00e9m n\u00e3o podem \u2013 nem devem \u2013 ser confundidas com a quest\u00e3o de prefer\u00eancia dos clientes por comprar de voc\u00ea ou dos concorrentes.<\/p>\n<h2>Visita de venda <em>vs<\/em> Visita de Fideliza\u00e7\u00e3o<\/h2>\n<p>Se toda vez que voc\u00ea visita ou entra em contato com um cliente no fundo o que quer \u00e9 fechar uma venda, ent\u00e3o n\u00e3o est\u00e1 pensando em fidelizar. N\u00e3o est\u00e1 investindo no relacionamento. Est\u00e1 simplesmente fazendo gest\u00e3o de carteira. Esse tipo de visita \u00e9 uma visita de venda, n\u00e3o uma visita de fideliza\u00e7\u00e3o ou de relacionamento.<\/p>\n<p>Fica f\u00e1cil de separar as duas coisas analisando a inten\u00e7\u00e3o: espero vender algo? Ou espero aprender algo?<\/p>\n<ul>\n<li><strong>Visitas ou contatos de gest\u00e3o de carteira t\u00eam inten\u00e7\u00e3o clara de revenda.<\/strong>\u00a0Inclusive existem indicadores espec\u00edficos para isso (taxa de positiva\u00e7\u00e3o, por exemplo). Nesses momentos h\u00e1 um sinal de R$ claro sendo monitorado.<\/li>\n<li><strong>Visitas ou contatos de relacionamento t\u00eam a inten\u00e7\u00e3o de saber mais sobre o cliente e, principalmente, entender sobre como podemos atend\u00ea-lo melhor.<\/strong>\u00a0Aqui n\u00e3o tem sinal de R$. \u00c9 um investimento da empresa que pode e deve benefici\u00e1-la no futuro, aumentando o<em>\u00a0lifetime value<\/em>\u00a0(o valor de um cliente para a empresa durante o per\u00edodo em que permanece ativo). Ao fazer esse tipo de visita, a empresa mostra que quer que o cliente permane\u00e7a por muito tempo comprando dela, em volumes est\u00e1veis ou crescentes.<\/li>\n<\/ul>\n<p>Recentemente fiz dois workshops sobre o assunto e, depois do choque inicial de descobrir que 95% do que \u00e9 feito n\u00e3o \u00e9 de verdade fideliza\u00e7\u00e3o, muitas empresas descobrem que t\u00eam, sim, algumas iniciativas em rela\u00e7\u00e3o a isso, s\u00f3 que elas est\u00e3o dispersas, sem foco, n\u00e3o s\u00e3o uma prioridade e, pior, n\u00e3o se mede como e nem se ajudam a aprofundar o relacionamento com clientes.<\/p>\n<p>Fica f\u00e1cil de reconhecer isso com tr\u00eas perguntas simples:<\/p>\n<ul>\n<li>Existe uma pessoa respons\u00e1vel s\u00f3 por trabalhar a fideliza\u00e7\u00e3o? Se fideliza\u00e7\u00e3o de clientes \u00e9 uma prioridade, quem \u00e9 respons\u00e1vel por isso?<\/li>\n<li>Como \u201cfidelidade\u201d \u00e9 definida e como \u00e9 mensurada? Existem indicadores espec\u00edficos em rela\u00e7\u00e3o \u00e0 fideliza\u00e7\u00e3o?<\/li>\n<li>Existe verba\/or\u00e7amento espec\u00edfico e exclusivo para isso?<\/li>\n<\/ul>\n<p>Em muitas empresas as iniciativas existem, s\u00e3o bem-intencionadas, est\u00e3o sendo executadas, mas como n\u00e3o tem foco nem prioridade, a for\u00e7a das a\u00e7\u00f5es acaba se perdendo.<\/p>\n<p>Na correria do dia a dia comercial, a\u00e7\u00f5es de curto prazo, com retorno r\u00e1pido, acabam soterrando qualquer iniciativa que demore mais para apresentar resultados, mesmo as mais estrat\u00e9gicas. Por isso as a\u00e7\u00f5es puramente de fideliza\u00e7\u00e3o\/relacionamento raramente avan\u00e7am ou s\u00e3o consideradas priorit\u00e1rias (mesmo que o discurso seja diferente, a realidade pr\u00e1tica \u00e9 essa).<\/p>\n<p>Para ajudar a incentivar cada vez mais as melhores pr\u00e1ticas, apresento a seguir algumas ideias que voc\u00ea poderia desenvolver na sua empresa com foco exclusivo em fideliza\u00e7\u00e3o e lealdade de clientes (se precisar de ajuda com treinamentos e consultoria nessa \u00e1rea, \u00e9 s\u00f3 avisar).<\/p>\n<p>As sugest\u00f5es s\u00e3o bem pr\u00e1ticas. A quest\u00e3o passa a ser ent\u00e3o priorizar qual delas funcionaria melhor na sua realidade atual e como fazer os ajustes necess\u00e1rios para implantar o projeto na sua empresa.<\/p>\n<p>Vamos l\u00e1!<\/p>\n<h2>25 ideias que voc\u00ea pode implantar na sua empresa para aumentar a lealdade e fidelizar clientes<\/h2>\n<ol>\n<li><strong>Criar grupos de apoio para clientes.<\/strong>\u00a0No IEV, por exemplo, temos coaches para os alunos das franquias. Na sua empresa, quando o cliente tem alguma d\u00favida, com quem fala? Outro ponto positivo dessa forma de pensar \u00e9 que tira o monop\u00f3lio do vendedor no relacionamento com o cliente, criando mais pontos de contato, outro item que aumenta fideliza\u00e7\u00e3o e lealdade.<\/li>\n<li><strong>Desenvolver um kit de boas-vindas para novas compras e recompras.<\/strong><\/li>\n<li><strong>Realizar pesquisas de satisfa\u00e7\u00e3o<\/strong>, com a inten\u00e7\u00e3o de melhorar o processo de compra e o atendimento e diminuir\/eliminar irritadores<\/li>\n<li><strong>Coletar depoimentos<\/strong>. S\u00f3 o fato de coletar depoimentos muitas vezes faz o pr\u00f3prio cliente sentir-se mais valorizado.<\/li>\n<li><strong>Reconhecer e recompensar indica\u00e7\u00f5es\/marketing boca a boca<\/strong>.<\/li>\n<li><strong>Dar respostas r\u00e1pidas a reclama\u00e7\u00f5es e resolver os problemas dos clientes<\/strong>\u00a0(\u00eanfase no resolver, sem\u00a0<em>enrolation<\/em>).<\/li>\n<li><strong>Dar respostas r\u00e1pidas a sugest\u00f5es de melhoria e\/ou de inova\u00e7\u00e3o<\/strong>\u00a0(novos produtos ou servi\u00e7os, por exemplo).<\/li>\n<li><strong>Fazer pesquisas de tend\u00eancia<\/strong>\u00a0na sua \u00e1rea\/setor\/regi\u00e3o e compartilhar resultados com clientes.<\/li>\n<li><strong>Promover visitas t\u00e9cnicas com clientes<\/strong>.<\/li>\n<li><strong>Estabelecer um processo de\u00a0<em>onboarding<\/em>\u00a0de clientes<\/strong>, ou o processo de dar boas vindas aos clientes, ensinando-os como aproveitar melhor a oportunidade tanto do produto\/servi\u00e7o que compraram\/adquiriram quanto sobre como aproveitar o relacionamento com voc\u00ea e sua empresa.<\/li>\n<li><strong>Criar um\u00a0<em>onboarding<\/em>\u00a0para vendedores<\/strong>, assunto pouqu\u00edssimo trabalhado, mas muito importante. Qual o processo de \u201cboas-vindas\u201d de um novo vendedor dentro da sua equipe?<\/li>\n<li><strong>Trabalhar para engajar a equipe<\/strong>. Fred Reichheld tem um cap\u00edtulo s\u00f3 sobre isso no livro\u00a0<em>Estrat\u00e9gias da lealdade<\/em>\u00a0(Ed. Campus). Uma equipe desengajada n\u00e3o ret\u00e9m clientes. Parece b\u00e1sico, mas muitos gestores n\u00e3o prestam aten\u00e7\u00e3o nisso. Pesquisas de clima interno que tenho feito com alunos t\u00eam feito muitos gestores ficarem bem surpresos em rela\u00e7\u00e3o aos seus n\u00fameros e ao posicionamento da equipe. A forma como um l\u00edder lidera a equipe impacta diretamente fideliza\u00e7\u00e3o de clientes, pois clima interno faz uma diferen\u00e7a tremenda!<\/li>\n<li><strong>Oferecer treinamentos adicionais aos clientes<\/strong>, quando for o caso (presencial e\/ou online).<\/li>\n<li><strong>Criar eventos exclusivos s\u00f3 para os clientes<\/strong>\u00a0(presenciais e\/ou online).<\/li>\n<li><strong>Valorizar datas comemorativas com clientes<\/strong>.<\/li>\n<li><strong>Dar brindes exclusivos para reconhecer e recompensar a fidelidade<\/strong>.<\/li>\n<li><strong>Desenvolver planos de milhagem<\/strong>\u00a0(tecnicamente, isso \u00e9 mais gest\u00e3o de carteira e de oportunidades do que fideliza\u00e7\u00e3o, pois est\u00e1 relacionado diretamente a recompensar compras e \u00e9, no fundo, um plano mais evolu\u00eddo de descontos. Por\u00e9m, como pode alterar prefer\u00eancias, pode ser inclu\u00eddo nesta lista).<\/li>\n<li><strong>Investir em\u00a0<em>branding<\/em>\/marca e rela\u00e7\u00f5es p\u00fablicas<\/strong>\u00a0(incluindo trabalhar com formadores de opini\u00e3o). Existem estudos que mostram que muitas vezes seus clientes prestam mais aten\u00e7\u00e3o nas propagandas do que potenciais clientes\/<em>prospects<\/em>, e que, dependendo do posicionamento, isso refor\u00e7a o pensamento de que tomaram a decis\u00e3o certa ao escolher voc\u00ea como fornecedor. Por isso muita aten\u00e7\u00e3o a quest\u00f5es promocionais!<\/li>\n<li><strong>Treinar a equipe de vendas<\/strong>. Vendedores competentes e mais bem preparados, al\u00e9m de mais engajados, atendem clientes de forma diferenciada.<\/li>\n<li><strong>Criar um comit\u00ea de clientes<\/strong>. Muitas empresas est\u00e3o come\u00e7ando a criar comit\u00eas de clientes, com um grupo de clientes reunindo-se regularmente para conversar, fazer sugest\u00f5es, interagir com a equipe, ajudar a planejar, opinar sobre mudan\u00e7as.<\/li>\n<li><strong>Criar um comit\u00ea \u201cKaizen\u201d<\/strong>. Esse \u00e9 um comit\u00ea interno, multidepartamental, com o foco exclusivo de avaliar reclama\u00e7\u00f5es e sugest\u00f5es de melhorias de clientes, implantar mudan\u00e7as e fazer os ajustes necess\u00e1rios para melhorar esses indicadores.<\/li>\n<li><strong>Ter uma PUV (Proposta \u00danica de Valor) real<\/strong>, comunicada e refor\u00e7ada de maneira clara, consistente e cont\u00ednua.<\/li>\n<li><strong>Segmentar suas iniciativas de prospec\u00e7\u00e3o de clientes<\/strong>\u00a0(fideliza\u00e7\u00e3o come\u00e7a na escolha correta de quem voc\u00ea atende).<\/li>\n<li><strong>Segmentar a carteira atual de clientes de forma mais completa<\/strong>\u00a0(indo al\u00e9m da curva ABC, que \u00e9 limitada a volume\/rentabilidade), entender as prioridades espec\u00edficas de cada um dos segmentos e trabalhar para criar\/refor\u00e7ar PUVs espec\u00edficas por segmento de clientes.<\/li>\n<li><strong>Demitir clientes desalinhados<\/strong>, vampiros, predadores.<\/li>\n<\/ol>\n<p>Se quiser, considere a lista acima de forma diferente: como diminuir e lidar de maneira inteligente e proativa com a potencial promiscuidade comercial de clientes. Talvez colocar dessa forma seja mais interessante em alguns casos.<\/p>\n<p>Perguntas\u00a0<em>coach<\/em>, para terminar:<\/p>\n<ol type=\"a\">\n<li>De 0 a 10, que nota voc\u00ea daria para seus processos e iniciativas de fideliza\u00e7\u00e3o de clientes (os puramente relacionados a aprofundar o relacionamento, e n\u00e3o apenas garantir uma compra imediata no contato sendo feito)?<\/li>\n<li>Existe uma pessoa respons\u00e1vel por fideliza\u00e7\u00e3o de clientes na sua empresa? Ela \u00e9 importante na hierarquia? (<em>Dica: deveria ser o mais alto poss\u00edvel dentro da hierarquia, afinal, a empresa inteira gira em torno disso<\/em>).<\/li>\n<li>Existem indicadores espec\u00edficos para avaliar a evolu\u00e7\u00e3o da fideliza\u00e7\u00e3o de clientes? H\u00e1, por exemplo, uma pesquisa de satisfa\u00e7\u00e3o n\u00e3o s\u00f3 em rela\u00e7\u00e3o ao produto\/servi\u00e7o\/solu\u00e7\u00e3o, mas ao processo de vendas e ao atendimento como um todo?<\/li>\n<li>H\u00e1 uma verba pr\u00f3pria para fideliza\u00e7\u00e3o de clientes?<\/li>\n<li>H\u00e1 um comit\u00ea interdepartamental para avaliar e agir sobre os assuntos espec\u00edficos ligados \u00e0 melhoria de processos que aumentariam as avalia\u00e7\u00f5es sendo dadas por clientes?<\/li>\n<li>Como reclama\u00e7\u00f5es e sugest\u00f5es de clientes s\u00e3o avaliadas?<\/li>\n<li>Como sugest\u00f5es de clientes s\u00e3o implantadas?<\/li>\n<li>Como clientes s\u00e3o recompensados e reconhecidos pela lealdade?<\/li>\n<li>Como a equipe de vendas \u00e9 recompensada e reconhecida pela lealdade dos clientes que atende?<\/li>\n<li>Como o resto da empresa \u00e9 recompensado e reconhecido pela lealdade dos clientes?<\/li>\n<li>Quais das ideias acima fariam a maior diferen\u00e7a na fideliza\u00e7\u00e3o e aumento de lealdade de clientes, se implantadas?<\/li>\n<\/ol>\n<p>Meu \u00faltimo desafio e um pedido: vamos trabalhar juntos para mudar esse cen\u00e1rio, onde todo mundo fala sobre como fideliza\u00e7\u00e3o \u00e9 importante, mas na pr\u00e1tica pouqu\u00edssima gente est\u00e1 fazendo algo de verdade em rela\u00e7\u00e3o a isso?<\/p>\n<p>A melhor forma de crescer de maneira sustent\u00e1vel (e de dormir tranquilo) \u00e9 parar de falar sobre isso e come\u00e7ar a fazer algo de maneira s\u00e9ria, organizada, planejada. Com indicadores, comit\u00ea, reuni\u00f5es peri\u00f3dicas, pessoa respons\u00e1vel.<\/p>\n<p>Clientes fi\u00e9is s\u00e3o excelentes vendedores (via boca a boca), excelentes inovadores (via sugest\u00f5es), excelentes cr\u00edticos (via reclama\u00e7\u00f5es) e s\u00e3o a melhor blindagem que uma empresa pode ter para o futuro.<\/p>\n<p>Assunto s\u00e9rio que merece ser tratado de forma s\u00e9ria. E n\u00e3o \u00e9 via palestra motivacional que se consegue isso, \u00e9 uma decis\u00e3o bem mais profunda e estrat\u00e9gica.<\/p>\n<p>Abra\u00e7o e boas vendas,<\/p>\n<p>Raul Candeloro<br \/>\nDiretor da VendaMais<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Artigo cedido pela Revista Venda Mais. Todos os direitos reservados. Fideliza\u00e7\u00e3o de clientes \u00e9 sempre um assunto \u201cquente\u201d nos meus workshops e cursos, e uma coisa fica evidente logo de cara: fideliza\u00e7\u00e3o (ou lealdade) de clientes \u00e9 mais ou menos como sexo entre adolescentes \u2013 muita gente fala mais do que faz, poucos fazem de [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":33801,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[906],"tags":[851,795],"lista-de-leitura":[],"listas_de_leitura":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.6.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>25 ideias para aumentar a lealdade e fidelizar clientes | Blog Agendor<\/title>\n<meta name=\"description\" content=\"Neste artigo de Raul Candeloro, da VendaMais, exclusivo para o blog do Agendor, o autor traz 25 dicas para fidelizar mais clientes e gerar mais vendas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.agendor.com.br\/blog\/ideias-fidelizar-clientes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"25 ideias para aumentar a lealdade e fidelizar clientes | Blog Agendor\" \/>\n<meta property=\"og:description\" content=\"Neste artigo de Raul Candeloro, da VendaMais, exclusivo para o blog do Agendor, o autor traz 25 dicas para fidelizar mais clientes e gerar mais vendas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.agendor.com.br\/blog\/ideias-fidelizar-clientes\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Agendor\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/agendor\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-13T11:00:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-18T18:40:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2020\/02\/10183155\/ideias-fidelizar-clientes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"501\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/posts\/33797"}],"collection":[{"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/comments?post=33797"}],"version-history":[{"count":0,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/posts\/33797\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/media\/33801"}],"wp:attachment":[{"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/media?parent=33797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/categories?post=33797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/tags?post=33797"},{"taxonomy":"lista-de-leitura","embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/lista-de-leitura?post=33797"},{"taxonomy":"listas_de_leitura","embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/listas_de_leitura?post=33797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}