{"id":2729,"date":"2021-07-26T16:00:00","date_gmt":"2021-07-26T19:00:00","guid":{"rendered":"http:\/\/www.agendor.com.br\/blog\/?p=2729"},"modified":"2021-08-14T10:58:51","modified_gmt":"2021-08-14T13:58:51","slug":"pipeline-de-vendas","status":"publish","type":"post","link":"https:\/\/www.agendor.com.br\/blog\/pipeline-de-vendas\/","title":{"rendered":"Como fazer gest\u00e3o de pipeline de vendas? como fazer? Passo a passo e vantagens"},"content":{"rendered":"\n<p><strong>A sua empresa trabalha com a gest\u00e3o de Pipeline de Vendas, organizando cada negocia\u00e7\u00e3o em etapas como Prospec\u00e7\u00e3o, Envio de Proposta, Follow-up e Fechamento?<\/strong><\/p>\n\n\n\n<p>Essa \u00e9 uma ferramenta poderosa para controlar, saber como est\u00e1 o andamento e projetar os resultados das vendas. Definindo as <strong>etapas em formato de Pipeline comercial<\/strong>, \u00e9 poss\u00edvel ter uma ideia de qual venda precisa de um foco maior e estimar o resultado das vendas do m\u00eas.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_17 counter-hierarchy counter-decimal\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\">O que voc&ecirc; vai conferir:<\/p>\n<span class=\"ez-toc-title-toggle\"><a class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" style=\"display: none;\"><i class=\"ez-toc-glyphicon ez-toc-icon-toggle\"><\/i><\/a><\/span><\/div>\n<nav><ul class=\"ez-toc-list ez-toc-list-level-1\"><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.agendor.com.br\/blog\/pipeline-de-vendas\/#O_que_e_pipeline_de_vendas\" title=\"O que \u00e9 pipeline de vendas?\">O que \u00e9 pipeline de vendas?<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.agendor.com.br\/blog\/pipeline-de-vendas\/#Quais_sao_as_vantagens_da_gestao_de_pipeline_de_vendas\" title=\"Quais s\u00e3o as vantagens da gest\u00e3o de pipeline de vendas?\">Quais s\u00e3o as vantagens da gest\u00e3o de pipeline de vendas?<\/a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.agendor.com.br\/blog\/pipeline-de-vendas\/#Reducao_do_tempo_do_ciclo_de_vendas\" title=\"Redu\u00e7\u00e3o do tempo do ciclo de vendas\">Redu\u00e7\u00e3o do tempo do ciclo de vendas<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.agendor.com.br\/blog\/pipeline-de-vendas\/#Facilidade_para_a_analise_do_desempenho_da_equipe_de_vendas\" title=\"Facilidade para a an\u00e1lise do desempenho da equipe de vendas\">Facilidade para a an\u00e1lise do desempenho da equipe de vendas<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.agendor.com.br\/blog\/pipeline-de-vendas\/#Maior_previsibilidade_e_controle_das_vendas\" title=\"Maior previsibilidade e controle das vendas\">Maior previsibilidade e controle das vendas<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.agendor.com.br\/blog\/pipeline-de-vendas\/#Auxilia_na_tomada_de_decisoes_comerciais_com_dados_relevantes\" title=\"Auxilia na tomada de decis\u00f5es comerciais com dados relevantes \">Auxilia na tomada de decis\u00f5es comerciais com dados relevantes <\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.agendor.com.br\/blog\/pipeline-de-vendas\/#Padronizacao_dos_processos_de_cada_etapa_de_negociacao\" title=\"Padroniza\u00e7\u00e3o dos processos de cada etapa de negocia\u00e7\u00e3o\">Padroniza\u00e7\u00e3o dos processos de cada etapa de negocia\u00e7\u00e3o<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.agendor.com.br\/blog\/pipeline-de-vendas\/#Visao_mais_ampla_das_oportunidades_de_venda\" title=\"Vis\u00e3o mais ampla das oportunidades de venda\">Vis\u00e3o mais ampla das oportunidades de venda<\/a><\/li><\/ul><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/www.agendor.com.br\/blog\/pipeline-de-vendas\/#Como_fazer_a_gestao_do_pipeline_de_vendas\" title=\"Como fazer a gest\u00e3o do pipeline de vendas?\">Como fazer a gest\u00e3o do pipeline de vendas?<\/a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/www.agendor.com.br\/blog\/pipeline-de-vendas\/#1_Tenha_a_quantidade_ideal_de_leads_em_seu_pipeline\" title=\"1. Tenha a quantidade ideal de leads em seu pipeline\">1. Tenha a quantidade ideal de leads em seu pipeline<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/www.agendor.com.br\/blog\/pipeline-de-vendas\/#2_Estabeleca_um_tempo_maximo_para_cada_etapa_no_funil\" title=\"2. Estabele\u00e7a um tempo m\u00e1ximo para cada etapa no funil\">2. Estabele\u00e7a um tempo m\u00e1ximo para cada etapa no funil<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/www.agendor.com.br\/blog\/pipeline-de-vendas\/#3_Estude_e_descubra_o_tempo_medio_de_cada_etapa_do_pipeline\" title=\"3. Estude e descubra o tempo m\u00e9dio de cada etapa do pipeline\">3. Estude e descubra o tempo m\u00e9dio de cada etapa do pipeline<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/www.agendor.com.br\/blog\/pipeline-de-vendas\/#4_Faca_contatos_relevantes_e_tenha_conversas_significativas\" title=\"4. Fa\u00e7a contatos relevantes e tenha conversas significativas\">4. Fa\u00e7a contatos relevantes e tenha conversas significativas<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/www.agendor.com.br\/blog\/pipeline-de-vendas\/#5_Descubra_as_melhores_tecnicas_de_vendas_para_seu_pipeline\" title=\"5. Descubra as melhores t\u00e9cnicas de vendas para seu pipeline\">5. Descubra as melhores t\u00e9cnicas de vendas para seu pipeline<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/www.agendor.com.br\/blog\/pipeline-de-vendas\/#6_Defina_criterios_claros_para_o_seus_vendedores\" title=\"6. Defina crit\u00e9rios claros para o seus vendedores \">6. Defina crit\u00e9rios claros para o seus vendedores <\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/www.agendor.com.br\/blog\/pipeline-de-vendas\/#7_Venda_para_quem_realmente_precisa_de_sua_solucao\" title=\"7. Venda para quem realmente precisa de sua solu\u00e7\u00e3o\">7. Venda para quem realmente precisa de sua solu\u00e7\u00e3o<\/a><\/li><\/ul><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/www.agendor.com.br\/blog\/pipeline-de-vendas\/#Como_trabalhar_a_gestao_de_pipeline_de_vendas_com_o_Agendor\" title=\"Como trabalhar a gest\u00e3o de pipeline de vendas com o Agendor\">Como trabalhar a gest\u00e3o de pipeline de vendas com o Agendor<\/a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/www.agendor.com.br\/blog\/pipeline-de-vendas\/#1_Defina_a_etapa_de_uma_negociacao\" title=\"1. Defina a etapa de uma negocia\u00e7\u00e3o\">1. Defina a etapa de uma negocia\u00e7\u00e3o<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/www.agendor.com.br\/blog\/pipeline-de-vendas\/#2_Ordene_por_evolucao_do_Pipeline_Comercial\" title=\"2. Ordene por evolu\u00e7\u00e3o do Pipeline Comercial\">2. Ordene por evolu\u00e7\u00e3o do Pipeline Comercial<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/www.agendor.com.br\/blog\/pipeline-de-vendas\/#3_Visualize_os_negocios_por_etapa\" title=\"3. Visualize os neg\u00f3cios por etapa\">3. Visualize os neg\u00f3cios por etapa<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-21\" href=\"https:\/\/www.agendor.com.br\/blog\/pipeline-de-vendas\/#4_Personalize_o_Pipeline_de_Vendas_para_a_sua_empresa\" title=\"4. Personalize o Pipeline de Vendas para a sua empresa\">4. Personalize o Pipeline de Vendas para a sua empresa<\/a><\/li><\/ul><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-22\" href=\"https:\/\/www.agendor.com.br\/blog\/pipeline-de-vendas\/#Indicadores_da_gestao_do_pipeline_de_vendas\" title=\"Indicadores da gest\u00e3o do pipeline de vendas\">Indicadores da gest\u00e3o do pipeline de vendas<\/a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-23\" href=\"https:\/\/www.agendor.com.br\/blog\/pipeline-de-vendas\/#Numero_de_leads_no_pipeline\" title=\"N\u00famero de leads no pipeline\">N\u00famero de leads no pipeline<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-24\" href=\"https:\/\/www.agendor.com.br\/blog\/pipeline-de-vendas\/#Ticket_medio\" title=\"Ticket m\u00e9dio\">Ticket m\u00e9dio<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-25\" href=\"https:\/\/www.agendor.com.br\/blog\/pipeline-de-vendas\/#Ciclo_de_vendas_medio\" title=\"Ciclo de vendas m\u00e9dio\">Ciclo de vendas m\u00e9dio<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-26\" href=\"https:\/\/www.agendor.com.br\/blog\/pipeline-de-vendas\/#Produtividade_da_equipe_de_vendas\" title=\"Produtividade da equipe de vendas \">Produtividade da equipe de vendas <\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"O_que_e_pipeline_de_vendas\"><\/span>O que \u00e9 pipeline de vendas?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Um <a href=\"https:\/\/www.agendor.com.br\/blog\/o-que-e-pipeline-de-vendas\/\">pipeline de vendas<\/a> \u00e9 um conceito que re\u00fane as etapas do processo de vendas e negocia\u00e7\u00e3o com os prospects de uma empresa. O principal <a href=\"https:\/\/www.agendor.com.br\/blog\/pipeiline-de-vendas-significado\/\">objetivo do conceito de pipeline de venda<\/a>s \u00e9 organizar os leads conforme cada etapa de negocia\u00e7\u00e3o, definindo quais os pr\u00f3ximos passos a serem feitos, como liga\u00e7\u00e3o, envio de e-mail ou proposta e e o andamento da convers\u00e3o.<\/p>\n\n\n\n<h2><span class=\"ez-toc-section\" id=\"Quais_sao_as_vantagens_da_gestao_de_pipeline_de_vendas\"><\/span>Quais s\u00e3o as vantagens da gest\u00e3o de pipeline de vendas?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Uma gest\u00e3o de pipeline de vendas traz uma s\u00e9rie de vantagens. Confira as melhores que v\u00e3o auxiliar no <a href=\"https:\/\/www.agendor.com.br\/blog\/dicas-como-aumentar-vendas-de-uma-empresa\/\">aumento de suas vendas!<\/a><\/p>\n\n\n\n<h3><span class=\"ez-toc-section\" id=\"Reducao_do_tempo_do_ciclo_de_vendas\"><\/span>Redu\u00e7\u00e3o do tempo do ciclo de vendas<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Uma das principais vantagens do pipeline de vendas \u00e9 a possibilidade de encurtar o ciclo de vendas de sua empresa. <\/p>\n\n\n\n<p>Imagine, por exemplo, que o topo do seu funil de vendas esteja cheio de leads desqualificados, o que faz com que seus vendedores percam muito tempo com pessoas n\u00e3o interessadas em suas solu\u00e7\u00f5es.<\/p>\n\n\n\n<p>Neste caso, a gest\u00e3o do pipeline procura trabalhar para chegar ao<strong> cliente certo<\/strong>, que tenha grande potencial de fechamento. Ent\u00e3o, estabelecer a\u00e7\u00f5es pr\u00e1ticas de acordo com cada etapa do pipeline de vendas auxilia na redu\u00e7\u00e3o do seu ciclo de vendas. <\/p>\n\n\n\n<ul><li><a href=\"https:\/\/www.agendor.com.br\/blog\/ciclo-de-vendas\/\">Como diminuir o ciclo de vendas de sua empresa?<\/a><\/li><\/ul>\n\n\n\n<h3><span class=\"ez-toc-section\" id=\"Facilidade_para_a_analise_do_desempenho_da_equipe_de_vendas\"><\/span>Facilidade para a an\u00e1lise do desempenho da equipe de vendas<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Com a ajuda de indicadores de vendas da gest\u00e3o de pipeline, \u00e9 poss\u00edvel obter uma grande vantagem para identificar e compreender o desempenho e processo da equipe de vendas.<\/p>\n\n\n\n<p>Ter essa no\u00e7\u00e3o do que seus vendedores est\u00e3o fazendo para atingir suas metas ao utilizar um funil de vendas permite otimiz\u00e1-lo para que saibam o que precisam fazer exatamente para obter melhores resultados.<\/p>\n\n\n\n<ul><li><a href=\"https:\/\/www.agendor.com.br\/blog\/metricas-e-indicadores\/\">M\u00e9tricas e indicadores para avaliar o desempenho de seus vendedores<\/a><\/li><\/ul>\n\n\n\n<h3><span class=\"ez-toc-section\" id=\"Maior_previsibilidade_e_controle_das_vendas\"><\/span>Maior previsibilidade e controle das vendas<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Neste momento, voc\u00ea consegue fazer uma previs\u00e3o de quantas vendas ser\u00e1 capaz de fechar at\u00e9 o final do m\u00eas?<\/p>\n\n\n\n<p>Um dos m\u00e9todos para conseguir prever e controlar suas vendas passa pelo funil de vendas, que pode auxiliar em seu potencial de fechamento.<\/p>\n\n\n\n<p>Este m\u00e9todo funciona por meio da an\u00e1lise de dados, como o n\u00famero total de neg\u00f3cios em cada etapa do pipeline e o valor total dos neg\u00f3cios em cada est\u00e1gio do funil de vendas tamb\u00e9m.<\/p>\n\n\n\n<ul><li><a href=\"https:\/\/www.agendor.com.br\/blog\/metodos-previsao-de-vendas\/\">3 m\u00e9todos de previs\u00e3o de vendas para aplicar na sua empresa<\/a><\/li><\/ul>\n\n\n\n<h3><span class=\"ez-toc-section\" id=\"Auxilia_na_tomada_de_decisoes_comerciais_com_dados_relevantes\"><\/span>Auxilia na tomada de decis\u00f5es comerciais com dados relevantes <span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Com todas as informa\u00e7\u00f5es da gest\u00e3o de pipeline de vendas em m\u00e3os, a tomada de decis\u00f5es fica muito mais f\u00e1cil, melhorando os resultados conforme os dados coletados.<\/p>\n\n\n\n<p>Podemos considerar essa vantagem da gest\u00e3o de pipeline como parte da intelig\u00eancia comercial. Ou seja, consiste em coletar dados sobre a jornada de compra dos clientes com o objetivo de analis\u00e1-las a fim de chegar a decis\u00f5es assertivas e s\u00f3lidas.<\/p>\n\n\n\n<ul><li><a href=\"https:\/\/www.agendor.com.br\/blog\/inteligencia-comercial\/\">Como impulsionar suas vendas usando a intelig\u00eancia comercial<\/a><\/li><\/ul>\n\n\n\n<h3><span class=\"ez-toc-section\" id=\"Padronizacao_dos_processos_de_cada_etapa_de_negociacao\"><\/span>Padroniza\u00e7\u00e3o dos processos de cada etapa de negocia\u00e7\u00e3o<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>De certa forma, cada empresa pode ter um processo com quantidades diferentes de etapas de negocia\u00e7\u00e3o. O livro &#8220;Como Chegar ao Sim&#8221; de Willian Ury, por exemplo, aborda 5 etapas para concluir um neg\u00f3cio.<\/p>\n\n\n\n<p>No entanto, o importante \u00e9 compreender como o seu pipeline de vendas funciona melhor por meio da gest\u00e3o. A partir de ent\u00e3o, voc\u00ea deve chegar a um padr\u00e3o que se encaixe com a sua companhia e aumente seus resultados.<\/p>\n\n\n\n<ul><li><a href=\"https:\/\/www.agendor.com.br\/blog\/etapas-da-negociacao\/\">Como seguir as 7 etapas da negocia\u00e7\u00e3o e entregar mais valor aos clientes<\/a><\/li><\/ul>\n\n\n\n<h3><span class=\"ez-toc-section\" id=\"Visao_mais_ampla_das_oportunidades_de_venda\"><\/span>Vis\u00e3o mais ampla das oportunidades de venda<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>A gest\u00e3o do pipeline de vendas \u00e9 uma das v\u00e1rias formas de obter um vis\u00e3o sobre como aproveitar melhor as oportunidades de vendas.<\/p>\n\n\n\n<p>Com o seu funil de vendas bem organizado em cada etapa do processo, \u00e9 poss\u00edvel enxergar qualquer gargalo e, ao mesmo tempo, ver onde est\u00e3o as verdadeiras oportunidades de fechar cada vez mais neg\u00f3cios!<\/p>\n\n\n\n<ul><li><a href=\"https:\/\/www.agendor.com.br\/blog\/gestao-das-oportunidades-de-vendas-aumentar\/\">5 dicas para melhorar a gest\u00e3o de oportunidade de vendas e aumentar resultados<\/a><\/li><\/ul>\n\n\n\n<h2><span class=\"ez-toc-section\" id=\"Como_fazer_a_gestao_do_pipeline_de_vendas\"><\/span>Como fazer a gest\u00e3o do pipeline de vendas?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><strong>Mas como fazer a gest\u00e3o do pipeline de vendas com o objetivo de maximizar o desempenho da equipe?<\/strong> Existem alguns passos muito importantes que devem ser seguidos para melhorar desempenho na gest\u00e3o do pipeline.<\/p>\n\n\n\n<h3><span class=\"ez-toc-section\" id=\"1_Tenha_a_quantidade_ideal_de_leads_em_seu_pipeline\"><\/span>1. Tenha a quantidade ideal de leads em seu pipeline<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Ter o topo de seu pipeline de vendas cheio de leads n\u00e3o significa, necessariamente, que as coisas v\u00e3o bem.<\/p>\n\n\n\n<p>Isso pode fazer com que seu vendedor acabe se concentrando em qualificar essa enorme quantidade de leads e negligencie outras etapas do pipeline de vendas, como negocia\u00e7\u00e3o e fechamento. <\/p>\n\n\n\n<p><strong>Por isso, alinhe claramente com o pessoal de marketing a quantidade necess\u00e1ria de leads por m\u00eas.<\/strong><\/p>\n\n\n\n<p>Fa\u00e7a o chamado <a href=\"https:\/\/www.agendor.com.br\/blog\/smarketing-resultados\/\"><strong>smarketing<\/strong><\/a> e, assim, foque na qualidade dos leads e n\u00e3o na quantidade. Dessa forma, sua equipe de vendas ter\u00e1 tempo suficiente para fazer a gest\u00e3o do pipeline de vendas, trabalhando com todos os leads em todas as etapas.<\/p>\n\n\n\n<p>Para facilitar o trabalho de <a href=\"https:\/\/pluga.co\/blog\/marketing\/qualificacao-de-leads\/\" target=\"_blank\" rel=\"noopener\"><strong>qualifica\u00e7\u00e3o de leads<\/strong><\/a>, use algumas dessas t\u00e9cnicas:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img src=\"https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2019\/01\/31132729\/Vendas_consultivas.png\" alt=\"\"\/><\/figure><\/div>\n\n\n\n<h3><span class=\"ez-toc-section\" id=\"2_Estabeleca_um_tempo_maximo_para_cada_etapa_no_funil\"><\/span>2. Estabele\u00e7a um tempo m\u00e1ximo para cada etapa no funil<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>\u00c9 preciso definir um tempo m\u00e1ximo que cada lead deve ser abordado enquanto estiver na mesma etapa do funil.<\/p>\n\n\n\n<p>Essa \u00e9 um uma quest\u00e3o fundamental da gest\u00e3o de pipeline de vendas que voc\u00ea precisa responder:<\/p>\n\n\n\n<p><strong>Qual o tempo m\u00e9dio que um cliente que fez uma compra leva em cada etapa do pipeline?<\/strong><\/p>\n\n\n\n<p>Para descobrir isso, use a <a href=\"https:\/\/www.siteware.com.br\/metodologias\/analise-de-pareto\/\" target=\"_blank\" rel=\"noopener\"><strong>regra de Pareto<\/strong><\/a>: 80% de suas vendas s\u00e3o proporcionadas por 20% de seus clientes. Analise o comportamento desses 20% em cada etapa do pipeline.<\/p>\n\n\n\n<p>Estude os dados de seu <a href=\"https:\/\/www.agendor.com.br\/\">CRM<\/a> e defina qual o tempo m\u00e1ximo que um vendedor deve fazer o <a href=\"https:\/\/www.agendor.com.br\/blog\/follow-up\/\" target=\"_blank\" rel=\"noopener\"><strong>follow-up<\/strong><\/a> de um lead em determinada etapa. Caso passe desse per\u00edodo, ele deve se dedicar a outros leads mais promissores.<\/p>\n\n\n\n<h3><span class=\"ez-toc-section\" id=\"3_Estude_e_descubra_o_tempo_medio_de_cada_etapa_do_pipeline\"><\/span>3. Estude e descubra o tempo m\u00e9dio de cada etapa do pipeline<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Se os leads levam muito tempo em uma etapa, ela virou um gargalo: tem algo errado com ela!<\/p>\n\n\n\n<p>Assim, se ao fazer a an\u00e1lise do tempo m\u00e9dio em cada etapa, perceber que uma delas parece estar &#8220;travando&#8221; o <a href=\"https:\/\/www.agendor.com.br\/blog\/etapas-do-processo-de-vendas\/\"><strong>processo de venda<\/strong><\/a>, estude-a com bastante cuidado e descubra o que fazer para que ela se tornar meia flu\u00edda.<\/p>\n\n\n\n<p>A melhor maneira de fazer isso \u00e9 conversando com os vendedores e tamb\u00e9m entrevistando clientes sobre sua experi\u00eancia de compra.<\/p>\n\n\n\n<h3><span class=\"ez-toc-section\" id=\"4_Faca_contatos_relevantes_e_tenha_conversas_significativas\"><\/span>4. Fa\u00e7a contatos relevantes e tenha conversas significativas<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>N\u00e3o existe nada pior que tomar o tempo do cliente com &#8220;conversa mole&#8221;. Ningu\u00e9m tem tempo a perder e todos querem alcan\u00e7ar altos n\u00edveis de produtividade.<\/p>\n\n\n\n<p>Por isso, toda conversa com seu cliente deve ser significativa. <strong>Isto \u00e9: j\u00e1 determinar quando, onde e qual ser\u00e1 o pr\u00f3ximo passo do relacionamento.<\/strong><\/p>\n\n\n\n<p>Veja mais neste post:&nbsp;<a href=\"https:\/\/www.agendor.com.br\/blog\/fluxo-de-vendas\/\"><strong>Usando conversas significativas para favorecer o fluxo de vendas<\/strong><\/a><\/p>\n\n\n\n<h3><span class=\"ez-toc-section\" id=\"5_Descubra_as_melhores_tecnicas_de_vendas_para_seu_pipeline\"><\/span>5. Descubra as melhores t\u00e9cnicas de vendas para seu pipeline<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Em casos isolados, pode at\u00e9 ser. Mas a verdade \u00e9 que a base da boa gest\u00e3o do pipeline de vendas est\u00e1 exatamente em descobrir quais procedimentos funcionam melhor em cada etapa, isto \u00e9: levam a mais avan\u00e7os no pipeline.<\/p>\n\n\n\n<p>Assim, voc\u00ea pode formalizar em um playbook e em treinamentos as melhores <a href=\"https:\/\/www.agendor.com.br\/blog\/tecnicas-de-vendas-e-atendimento\/\" target=\"_blank\" rel=\"noopener\"><strong>t\u00e9cnicas de vendas<\/strong><\/a> a serem usadas ao longo do pipeline.<\/p>\n\n\n\n<p>Passar as melhores pr\u00e1ticas de vendas para os vendedores \u00e9 fundamental. Por isso, use e abuse das informa\u00e7\u00f5es de seu CRM com esse objetivo: <em><strong>descobrir o que realmente funciona [para todos!]<\/strong>.<\/em><\/p>\n\n\n\n<p>Por exemplo, muitos vendedores focam em dar descontos para fechar vendas. Mas essa n\u00e3o \u00e9 uma boa pr\u00e1tica. Descubra como mostrar valor aos seu leads ao longo de cada etapa do funil de vendas.<\/p>\n\n\n\n<p>Leia tamb\u00e9m:&nbsp;<a href=\"https:\/\/www.agendor.com.br\/blog\/como-usar-crm-tecnologia-da-informacao\/\"><strong>Como usar o CRM e a tecnologia da informa\u00e7\u00e3o para atingir os melhores resultados em sua empresa?<\/strong><\/a><\/p>\n\n\n\n<h3><span class=\"ez-toc-section\" id=\"6_Defina_criterios_claros_para_o_seus_vendedores\"><\/span>6. Defina crit\u00e9rios claros para o seus vendedores <span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p><em><strong>Defina crit\u00e9rios claros para que seus vendedores possam avan\u00e7ar leads com seguran\u00e7a pelo funil de vendas. Assim, ter\u00e3o certeza de que s\u00e3o mesmo qualificados.<\/strong><\/em><\/p>\n\n\n\n<p>Por isso, para promover uma adequada gest\u00e3o do pipeline de vendas, estude com cuidado o que caracteriza a passagem de uma etapa para outra. E s\u00f3 permita que seus vendedores avancem os leads no pipeline se se encaixarem nesses crit\u00e9rios.<\/p>\n\n\n\n<p><strong>Por exemplo, quando um lead muda da etapa de &#8220;apresenta\u00e7\u00e3o da solu\u00e7\u00e3o&#8221; para a de &#8220;negocia\u00e7\u00e3o&#8221;? <\/strong><\/p>\n\n\n\n<p>Talvez quando responda a uma proposta comercial fazendo algumas altera\u00e7\u00f5es. Defina esse tipo de crit\u00e9rio objetivo e deixe seus vendedores trabalharem com mais assertividade.<\/p>\n\n\n\n<h3><span class=\"ez-toc-section\" id=\"7_Venda_para_quem_realmente_precisa_de_sua_solucao\"><\/span>7. Venda para quem realmente precisa de sua solu\u00e7\u00e3o<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p><strong>Esse \u00e9 o pior erro que vendedor pode cometer!<\/strong><\/p>\n\n\n\n<p>Vender para clientes que, na verdade, n\u00e3o precisam de fato das solu\u00e7\u00f5es que sua empresa vende, vai levar a uma enorme perda de clientes no futuro (<a href=\"https:\/\/www.heflo.com\/pt-br\/marketing\/como-calcular-taxa-de-churn\/\" target=\"_blank\" rel=\"noopener\"><strong>taxa de churn<\/strong><\/a>).<\/p>\n\n\n\n<p>Assim, pode ser que nesse curto per\u00edodo de perman\u00eancia na empresa n\u00e3o &#8220;paguem&#8221; o <a href=\"https:\/\/www.agendor.com.br\/blog\/custo-de-aquisicao-de-clientes\/\" target=\"_blank\" rel=\"noopener\"><strong>Custo de Aquisi\u00e7\u00e3o de Clientes<\/strong><\/a> (CAC). Al\u00e9m disso, podem se tornar detratores de sua marca.<\/p>\n\n\n\n<p>E lembre-se, a opini\u00e3o de pessoas na m\u00eddias sociais \u00e9 um dos <a href=\"https:\/\/mindminers.com\/blog\/fatores-que-influenciam-comportamento-do-consumidor\/\"><strong>fatores que influenciam o comportamento de compra<\/strong><\/a>. Por isso, evite vender a qualquer custo!<\/p>\n\n\n\n<p><strong><em>Em resumo, s\u00f3 venda para quem realmente vai se beneficiar de sua solu\u00e7\u00e3o.<\/em><\/strong><\/p>\n\n\n\n<p>Este post pode deixar isso mais claro:&nbsp;<a href=\"https:\/\/www.agendor.com.br\/blog\/customer-sucess-o-que-e-crm\/\" target=\"_blank\" rel=\"noopener\"><strong>O que \u00e9 Customer Success e seus 4 principais desafios<\/strong><\/a><\/p>\n\n\n\n<p>Voc\u00ea viu, at\u00e9 agora, o que \u00e9 e como fazer a gest\u00e3o do pipeline de vendas, mas sabe como criar um? Ent\u00e3o, confira este infogr\u00e1fico:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img src=\"https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2019\/03\/18164412\/o-que-e-pipeline-de-vendas1.gif\" alt=\"\"\/><\/figure><\/div>\n\n\n\n<p>Quer descobrir como formalizar as etapas de vendas e criar um pipeline? Baixe nosso e-book gratuito:&nbsp;<a href=\"http:\/\/materiais.agendor.com.br\/como-usar-o-agendor-para-criar-um-processo-de-vendas\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Como usar o Agendor para criar um processo de vendas e vender mais<\/strong><\/a><\/p>\n\n\n\n<h2><span class=\"ez-toc-section\" id=\"Como_trabalhar_a_gestao_de_pipeline_de_vendas_com_o_Agendor\"><\/span>Como trabalhar a gest\u00e3o de pipeline de vendas com o Agendor<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>O <a href=\"https:\/\/www.agendor.com.br\/\">Agendor<\/a> permite que voc\u00ea trabalhe o Pipeline de Vendas de sua empresa, controlando e visualizando facilmente as etapas de cada negocia\u00e7\u00e3o. Por padr\u00e3o, o Agendor j\u00e1 vem configurado com 4 etapas (Contato, Envio de Proposta, Follow-up e Fechamento), mas voc\u00ea pode <strong>personalizar o Pipeline<\/strong> especificamente para sua empresa!<\/p>\n\n\n\n<p>A vantagem de personalizar o <strong>Pipeline de Comercial&nbsp;para a sua empresa<\/strong>, \u00e9 que voc\u00ea pode usar os nomes mais adequados nas etapas e organizar o Pipeline &nbsp;de vendas em at\u00e9 10 etapas.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img width=\"681\" height=\"341\" src=\"https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2016\/12\/22165200\/pipeline-agendor1.png\" alt=\"pipeline-agendor\" class=\"wp-image-31166\" srcset=\"https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2016\/12\/22165200\/pipeline-agendor1.png 681w, https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2016\/12\/22165200\/pipeline-agendor1-640x320.png 640w\" sizes=\"(max-width: 681px) 100vw, 681px\" \/><\/figure><\/div>\n\n\n\n<p>Antes de conferir como \u00e9 f\u00e1cil usar o Agendor para controlar seu pipeline de vendas, que tal baixar um e-book que trata exatamente de como implantar o processo de vendas em seu neg\u00f3cio?<\/p>\n\n\n\n<p>Baixe agora:&nbsp;<strong><a href=\"http:\/\/materiais.agendor.com.br\/guia-como-elaborar-e-implementar-o-processo-de-vendas\" target=\"_blank\" rel=\"noopener\">Guia: como elaborar e implementar&nbsp;o processo de vendas<\/a><\/strong><\/p>\n\n\n\n<h3><span class=\"ez-toc-section\" id=\"1_Defina_a_etapa_de_uma_negociacao\"><\/span>1. Defina a etapa de uma negocia\u00e7\u00e3o<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>N\u00f3s estabelecemos um objetivo para n\u00f3s mesmos: a defini\u00e7\u00e3o e altera\u00e7\u00e3o das etapas dos neg\u00f3cios no Agendor deve ser algo muito f\u00e1cil e r\u00e1pido de ser feito.<\/p>\n\n\n\n<p>Como resultado, as <strong>etapas do Pipeline de Vendas<\/strong> podem ser definidas com um \u00fanico clique.<\/p>\n\n\n\n<h3><span class=\"ez-toc-section\" id=\"2_Ordene_por_evolucao_do_Pipeline_Comercial\"><\/span>2. Ordene por evolu\u00e7\u00e3o do Pipeline Comercial<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Precisa saber quais s\u00e3o as negocia\u00e7\u00f5es que est\u00e3o mais pr\u00f3ximas do fechamento? Ou ent\u00e3o, aquelas que precisam de uma aten\u00e7\u00e3o especial primeiro, pois est\u00e3o no <strong>in\u00edcio do Pipeline de Vendas<\/strong>?<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"http:\/\/www.agendor.com.br\/blog\/wp-content\/uploads\/2012\/11\/ordenando-pipeline-vendas.jpg\" rel=\"colorbox\"><img width=\"600\" height=\"305\" src=\"http:\/\/www.agendor.com.br\/blog\/wp-content\/uploads\/2012\/11\/ordenando-pipeline-vendas.jpg\" alt=\"Pipeline de Vendas\" class=\"wp-image-2750\" title=\"Ordenando o Pipeline de Vendas por andamento\" srcset=\"https:\/\/www.agendor.com.br\/blog\/wp-content\/uploads\/2012\/11\/ordenando-pipeline-vendas.jpg 600w, https:\/\/www.agendor.com.br\/blog\/wp-content\/uploads\/2012\/11\/ordenando-pipeline-vendas-300x152.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure><\/div>\n\n\n\n<p>Use a ordena\u00e7\u00e3o por Etapa na aba Neg\u00f3cios: &#8220;Maior &#8211; Menor&#8221; mostrar\u00e1 as que est\u00e3o mais pr\u00f3ximas do fechamento em primeiro. &#8220;Menor &#8211; Maior&#8221; mostrar\u00e1 as que est\u00e3o no in\u00edcio do Pipeline de Vendas.<\/p>\n\n\n\n<h3><span class=\"ez-toc-section\" id=\"3_Visualize_os_negocios_por_etapa\"><\/span>3. Visualize os neg\u00f3cios por etapa<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Voc\u00ea pode visualizar somente os neg\u00f3cios que est\u00e3o na etapa de &#8220;envio de proposta&#8221;, &#8220;prospec\u00e7\u00e3o&#8221;, ou qualquer outra etapa que voc\u00ea personalizou para a sua empresa.<\/p>\n\n\n\n<p>Para isso, h\u00e1 o<strong> filtro por Etapa na aba Neg\u00f3cios<\/strong>. Usando-o, ser\u00e3o mostrados somente os neg\u00f3cios que est\u00e3o na etapa que voc\u00ea selecionou.<\/p>\n\n\n\n<p><em>Certo, mas como eu fa\u00e7o para personalizar o Pipeline de Vendas para a minha empresa?<\/em><\/p>\n\n\n\n<h3><span class=\"ez-toc-section\" id=\"4_Personalize_o_Pipeline_de_Vendas_para_a_sua_empresa\"><\/span>4. Personalize o Pipeline de Vendas para a sua empresa<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Personalizar o Pipeline \u00e9 t\u00e3o simples quanto mudar as etapas de um neg\u00f3cio. Basta clicar em &#8220;Personalizar Etapas de Venda&#8221; na aba Neg\u00f3cios ou acessar o Menu &gt; <a href=\"http:\/\/www.agendor.com.br\/sistema\/configuracoes\/\" target=\"_blank\" rel=\"noopener\">Configura\u00e7\u00f5es<\/a>.<\/p>\n\n\n\n<p>No campo que \u00e9 mostrado, altere os nomes das etapas de seu pipeline comercial separando-os com v\u00edrgulas. Se j\u00e1 houverem neg\u00f3cios com etapas definidas, o Agendor lhe mostrar\u00e1 uma tela para que voc\u00ea fa\u00e7a a correspond\u00eancia das etapas.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img width=\"600\" height=\"290\" src=\"https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2019\/12\/04150543\/exemplo-pipeline-vendas-agendor.png\" alt=\"exemplo-pipeline-vendas-agendor\" class=\"wp-image-33200\"\/><\/figure><\/div>\n\n\n\n<p><strong>Aprofunde seus conhecimentos sobre pipeline de vendas: <\/strong><\/p>\n\n\n\n<ul><li><a href=\"https:\/\/www.agendor.com.br\/blog\/como-montar-um-pipeline-de-vendas\/\">Como montar um pipeline de vendas: passo a passo<\/a><\/li><li><a href=\"https:\/\/www.agendor.com.br\/blog\/modelo-pipeline-gestao\/\">Modelo de pipeline de vendas &#8211; Aprenda como funciona e melhore suas habilidades<\/a><\/li><\/ul>\n\n\n\n<h2><span class=\"ez-toc-section\" id=\"Indicadores_da_gestao_do_pipeline_de_vendas\"><\/span>Indicadores da gest\u00e3o do pipeline de vendas<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Para finalizar este artigo com chave de ouro, tamb\u00e9m precisamos conversar sobre indicadores de vendas baseados na gest\u00e3o do seu pipeline! <\/p>\n\n\n\n<p>Selecionamos os mais importantes para voc\u00ea ficar de olho e coletar dados sempre pensando na otimiza\u00e7\u00e3o do seu neg\u00f3cio!<\/p>\n\n\n\n<h3><span class=\"ez-toc-section\" id=\"Numero_de_leads_no_pipeline\"><\/span>N\u00famero de leads no pipeline<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>A gest\u00e3o do pipeline de vendas deve obter total controle do n\u00famero de leads que est\u00e3o em cada etapa do funil. <\/p>\n\n\n\n<p>\u00c9 essencial evitar que o topo do seu pipeline de vendas fique lotada de leads que v\u00e3o apenas fazer sua equipe de vendas perder tempo. Por isso, a experi\u00eancia aqui pode ser um fator determinante para saber separar os leads que n\u00e3o v\u00e3o converter em vendas.<\/p>\n\n\n\n<h3><span class=\"ez-toc-section\" id=\"Ticket_medio\"><\/span>Ticket m\u00e9dio<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>O <a href=\"https:\/\/www.agendor.com.br\/blog\/o-que-e-ticket-medio\/\">ticket m\u00e9dio<\/a> tamb\u00e9m \u00e9 um indicador de vendas de suma importante para o seu funil. Descobrir a m\u00e9dia de cada venda e negocia\u00e7\u00e3o da empresa permite avaliar o desempenho dos neg\u00f3cios e o potencial de compra dos clientes. <\/p>\n\n\n\n<p>\u00c9 um KPI muito utilizado para planejar a otimiza\u00e7\u00e3o do <a href=\"https:\/\/www.agendor.com.br\/blog\/sales-pipeline\/\">sales pipeline,<\/a> al\u00e9m de melhorar a previsibilidade das vendas e a tomada de decis\u00e3o. <\/p>\n\n\n\n<h3><span class=\"ez-toc-section\" id=\"Ciclo_de_vendas_medio\"><\/span><strong>Ciclo de vendas m\u00e9dio<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Como dissemos nas vantagens da gest\u00e3o do pipeline de vendas, \u00e9 poss\u00edvel encurtar o ciclo de vendas. No entanto, para isso voc\u00ea deve <a href=\"https:\/\/www.agendor.com.br\/blog\/ciclo-vendas-negocios\/\">mensurar o atual ciclo de vendas do seu neg\u00f3cio<\/a> por meio dos indicadores.<\/p>\n\n\n\n<h3><span class=\"ez-toc-section\" id=\"Produtividade_da_equipe_de_vendas\"><\/span><strong>Produtividade da equipe de vendas<\/strong> <span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Este indicador de vendas permite que voc\u00ea identifique a rela\u00e7\u00e3o de oportunidades e fechamentos de vendas. Assim, voc\u00ea pode analisar a equipe e tra\u00e7ar quais planos de a\u00e7\u00e3o ser\u00e3o necess\u00e1rios para aumentar a produtividade e efici\u00eancia.<\/p>\n\n\n\n<p>Quer ainda mais informa\u00e7\u00f5es sobre como usar o Agendor e criar um pipeline de vendas eficiente? <strong>Confira alguns de nossos e-books:<\/strong><\/p>\n\n\n\n<ul><li><strong><a href=\"http:\/\/materiais.agendor.com.br\/como-usar-o-agendor-para-criar-um-processo-de-vendas\">Como usar o Agendor para criar um processo de vendas e vender mais<\/a><\/strong><\/li><li><strong><a href=\"http:\/\/materiais.agendor.com.br\/como-usar-o-agendor-para-fazer-follow-up-com-clientes\">Como usar o Agendor para&nbsp;fazer follow-up com clientes<\/a><\/strong><\/li><li><strong><a href=\"http:\/\/materiais.agendor.com.br\/como-o-agendor-pode-ajudar-a-vencer-objecoes-durante-suas-negociacoes\">Como o Agendor pode ajudar a vencer obje\u00e7\u00f5es durante suas negocia\u00e7\u00f5es<\/a><\/strong><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>A sua empresa trabalha com a gest\u00e3o de Pipeline de Vendas, organizando cada negocia\u00e7\u00e3o em etapas como Prospec\u00e7\u00e3o, Envio de Proposta, Follow-up e Fechamento? Essa \u00e9 uma ferramenta poderosa para controlar, saber como est\u00e1 o andamento e projetar os resultados das vendas. Definindo as etapas em formato de Pipeline comercial, \u00e9 poss\u00edvel ter uma ideia [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":39358,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[886],"tags":[795,193],"lista-de-leitura":[],"listas_de_leitura":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.6.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gest\u00e3o de pipeline de vendas: como fazer, vantagens e indicadores<\/title>\n<meta name=\"description\" content=\"Veja as vantagens e como fazer uma boa gest\u00e3o de pipeline de vendas! Prospec\u00e7\u00e3o, Envio de Proposta, Follow-up e Fechamento com o Agendor.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.agendor.com.br\/blog\/pipeline-de-vendas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gest\u00e3o de pipeline de vendas: como fazer, vantagens e indicadores\" \/>\n<meta property=\"og:description\" content=\"Veja as vantagens e como fazer uma boa gest\u00e3o de pipeline de vendas! Prospec\u00e7\u00e3o, Envio de Proposta, Follow-up e Fechamento com o Agendor.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.agendor.com.br\/blog\/pipeline-de-vendas\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Agendor\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/agendor\" \/>\n<meta property=\"article:author\" content=\"https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2026\/01\/26125024\/julio-paulillo-agendor-2025-1-scaled.jpg\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-26T19:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-14T13:58:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2021\/07\/14104135\/gestao-pipeline-de-vendas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/posts\/2729"}],"collection":[{"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/comments?post=2729"}],"version-history":[{"count":0,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/posts\/2729\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/media\/39358"}],"wp:attachment":[{"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/media?parent=2729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/categories?post=2729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/tags?post=2729"},{"taxonomy":"lista-de-leitura","embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/lista-de-leitura?post=2729"},{"taxonomy":"listas_de_leitura","embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/listas_de_leitura?post=2729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}