{"id":22181,"date":"2016-10-31T08:00:10","date_gmt":"2016-10-31T10:00:10","guid":{"rendered":"http:\/\/www.agendor.com.br\/blog\/?p=22181"},"modified":"2023-12-21T12:19:42","modified_gmt":"2023-12-21T15:19:42","slug":"case-de-sucesso-com-o-agendor-sollus-tecnologia","status":"publish","type":"post","link":"https:\/\/www.agendor.com.br\/blog\/case-de-sucesso-com-o-agendor-sollus-tecnologia\/","title":{"rendered":"Case de sucesso com o Agendor: Sollus Tecnologia"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">A Sollus Tecnologia, empresa do ramo de equipamentos para controle de ponto e acesso, come\u00e7ou suas atividades em 1998. Desde ent\u00e3o, o grupo tem como foco a melhoria cont\u00ednua de seus servi\u00e7os e solu\u00e7\u00f5es.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para proporcionar aos clientes confiabilidade e satisfa\u00e7\u00e3o em rela\u00e7\u00e3o aos produtos e servi\u00e7os oferecidos, a empresa conta com ferramentas para controlar e aperfei\u00e7oar processos. E o Agendor \u00e9 uma delas! <\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cCom o Agendor, obtivemos como resultados: organiza\u00e7\u00e3o, um aumento de aproximadamente tr\u00eas vezes o n\u00famero de clientes e reconhecimento da melhoria do atendimento, retorno de liga\u00e7\u00f5es, entre outras a\u00e7\u00f5es\u201d, indica M\u00e1rcia Lima, consultora comercial da Sollus Tecnologia.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Conhe\u00e7a o caso de sucesso da Sollus Tecnologia, um cliente Agendor, sobre os benef\u00edcios obtidos com o uso da plataforma. <\/span><a href=\"http:\/\/www.agendor.com.br\/clientes\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Confira mais depoimentos em nosso site<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><!--more--><\/p>\n<p><img class=\"alignnone size-large wp-image-22315\" src=\"https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2016\/10\/21211710\/Sollus-Tecnologia-600x700.jpg\" alt=\"sollus-tecnologia\" width=\"600\" height=\"700\" srcset=\"https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2016\/10\/21211710\/Sollus-Tecnologia.jpg 600w, https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2016\/10\/21211710\/Sollus-Tecnologia-257x300.jpg 257w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Entre as funcionalidades destacadas por M\u00e1rcia Lima, est\u00e1 a de <\/span><b>Follow-up de clientes<\/b><span style=\"font-weight: 400;\">, que funciona basicamente da seguinte maneira: todos os dias \u00e0s 7h da manh\u00e3 e sempre 1h antes do prazo de uma tarefa, o Agendor envia um resumo com tudo que precisa fazer. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em outras palavras, o Agendor n\u00e3o deixa voc\u00ea e os profissionais do seu time esquecerem seus compromissos. Todos recebem lembretes de visitas agendadas, liga\u00e7\u00f5es a serem feitas e outras atividades, tanto por email como pelos aplicativos. \u201c\u00c9 realmente muito boa a ferramenta para agendamentos das atividades cotidianas\u201d, detalha a consultora.<\/span><\/p>\n<p><b>A equipe Agendor fica muito feliz em colaborar para o crescimento<\/b><span style=\"font-weight: 400;\"> da Sollus Tecnologia. Desejamos sempre muito sucesso para a empresa!<\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">Antes do Agendor, nossa maior dificuldade era manter em ordem todas as liga\u00e7\u00f5es efetuadas no dia a dia, enfim, o retorno ao cliente. Hoje, a praticidade de ter \u201calgu\u00e9m\u201d que encaminhe um e-mail lembrando da atividade, otimizou bastante a rotina comercial.<\/span><\/i><\/p>\n<p><i><span style=\"font-weight: 400;\">Como resultado, a organiza\u00e7\u00e3o foi a principal vantagem, seguida do aumento de aproximadamente tr\u00eas vezes o n\u00famero de clientes e reconhecimento <\/span><\/i><i><span style=\"font-weight: 400;\">\u2013 <\/span><\/i><i><span style=\"font-weight: 400;\">o mais significativo \u00e9 que o cliente reconhece a melhoria no atendimento, retorno das liga\u00e7\u00f5es em dias e hor\u00e1rios pr\u00e9-agendados, entre outras a\u00e7\u00f5es.<\/span><\/i><\/p>\n<p><i><span style=\"font-weight: 400;\">M\u00e1rcia Lima, consultora comercial da <\/span><\/i><a href=\"http:\/\/www.sollustecnologia.com\/\" target=\"_blank\" rel=\"noopener\"><i><span style=\"font-weight: 400;\">Sollus Tecnologia<\/span><\/i><\/a><\/p>\n<div id=\"attachment_22317\" style=\"width: 610px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-22317\" class=\"size-large wp-image-22317\" src=\"https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2016\/10\/31100010\/eye-319668_640-600x398.jpg\" alt=\"Case de sucesso\" width=\"600\" height=\"398\" srcset=\"https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2016\/10\/31100010\/eye-319668_640-600x398.jpg 600w, https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2016\/10\/31100010\/eye-319668_640-300x199.jpg 300w, https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2016\/10\/31100010\/eye-319668_640.jpg 640w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><p id=\"caption-attachment-22317\" class=\"wp-caption-text\">Case de Sucesso com o Agendor: Sollus Tecnologia<\/p><\/div>\n<p><strong>Saiba mais sobre como o aplicativo Agendor pode ajud\u00e1-lo com o follow-up! Acesse: <a href=\"http:\/\/materiais.agendor.com.br\/como-usar-o-agendor-para-fazer-follow-up-com-clientes\" target=\"_blank\" rel=\"noopener\">Como usar o Agendor para fazer follow-up com clientes<\/a> e <a href=\"http:\/\/materiais.agendor.com.br\/guia-como-ter-sucesso-com-follow-up\" target=\"_blank\" rel=\"noopener\">Guia: como ter sucesso com o follow-up<\/a><\/strong><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Sollus Tecnologia, empresa do ramo de equipamentos para controle de ponto e acesso, come\u00e7ou suas atividades em 1998. Desde ent\u00e3o, o grupo tem como foco a melhoria cont\u00ednua de seus servi\u00e7os e solu\u00e7\u00f5es. Para proporcionar aos clientes confiabilidade e satisfa\u00e7\u00e3o em rela\u00e7\u00e3o aos produtos e servi\u00e7os oferecidos, a empresa conta com ferramentas para controlar [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":22184,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[881],"tags":[17,796],"lista-de-leitura":[],"listas_de_leitura":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.6.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Case de sucesso com o Agendor: Sollus Tecnologia<\/title>\n<meta name=\"description\" content=\"Com o Agendor, obtivemos como resultados: organiza\u00e7\u00e3o, um aumento de aproximadamente tr\u00eas vezes o n\u00famero de clientes e reconhecimento da melhoria do atendimento.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.agendor.com.br\/blog\/case-de-sucesso-com-o-agendor-sollus-tecnologia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Case de sucesso com o Agendor: Sollus Tecnologia\" \/>\n<meta property=\"og:description\" content=\"Com o Agendor, obtivemos como resultados: organiza\u00e7\u00e3o, um aumento de aproximadamente tr\u00eas vezes o n\u00famero de clientes e reconhecimento da melhoria do atendimento.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.agendor.com.br\/blog\/case-de-sucesso-com-o-agendor-sollus-tecnologia\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Agendor\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/agendor\" \/>\n<meta property=\"article:author\" content=\"https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2026\/01\/26125024\/julio-paulillo-agendor-2025-1-scaled.jpg\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-31T10:00:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-21T15:19:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agendor-blog-uploads.s3.sa-east-1.amazonaws.com\/2016\/10\/21185814\/finger.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1293\" \/>\n\t<meta property=\"og:image:height\" content=\"1293\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/posts\/22181"}],"collection":[{"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/comments?post=22181"}],"version-history":[{"count":0,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/posts\/22181\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/media\/22184"}],"wp:attachment":[{"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/media?parent=22181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/categories?post=22181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/tags?post=22181"},{"taxonomy":"lista-de-leitura","embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/lista-de-leitura?post=22181"},{"taxonomy":"listas_de_leitura","embeddable":true,"href":"https:\/\/www.agendor.com.br\/blog\/wp-json\/wp\/v2\/listas_de_leitura?post=22181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}